{"id":98175,"date":"2025-05-02T04:21:13","date_gmt":"2025-05-02T03:21:13","guid":{"rendered":"https:\/\/blog.juandesouza.com\/?p=98175"},"modified":"2025-05-02T04:21:13","modified_gmt":"2025-05-02T03:21:13","slug":"review-tetris-effect-connected","status":"publish","type":"post","link":"https:\/\/blog.juandesouza.com\/fr\/games\/review-tetris-effect-connected\/","title":{"rendered":"Review: Tetris Effect Connected"},"content":{"rendered":"<p>J&#039;ai d\u00e9couvert pour la premi\u00e8re fois <strong>Tetris\u202fEffect:\u202fConnected<\/strong> D\u00e9but 2021, \u00e0 l&#039;\u00e9poque o\u00f9 il \u00e9tait confortablement install\u00e9 dans la biblioth\u00e8que Xbox Game Pass. \u00ab C&#039;est Tetris, comment pourrait-il \u00eatre diff\u00e9rent ? \u00bb me suis-je dit, me pr\u00e9parant \u00e0 une petite bouff\u00e9e de nostalgie avant d&#039;aller me coucher. Trois heures hypnotiques plus tard, j&#039;avais les yeux \u00e9carquill\u00e9s, un casque viss\u00e9 sur les oreilles, convaincu d&#039;avoir jou\u00e9 \u00e0 la version la plus transformatrice du jeu de puzzle classique d&#039;Alexey Pajitnov depuis l&#039;\u00e8re Juan sur PlayStation.<\/p>\n<p>Le jeu a quitt\u00e9 le Game Pass en avril 2023 et est d\u00e9sormais disponible uniquement en t\u00e9l\u00e9chargement payant. Pourtant, rien n&#039;a chang\u00e9 dans mon rituel du soir\u00a0: lumi\u00e8res tamis\u00e9es, volume \u00e0 fond, morceaux qui pleuvent en rythme avec une musique qui semble s&#039;accorder \u00e0 mon rythme cardiaque. Apr\u00e8s des centaines de sessions sur console, PC et, plus \u00e9poustouflant encore, en VR, voici pourquoi j&#039;y crois. <em>Tetris\u202fEffect:\u202fConnected<\/em> est essentiel pour tous ceux qui pensent avoir d\u00e9j\u00e0 \u00ab tout vu \u00bb dans le genre du puzzle.<\/p><div id=\"juand-4275938513\" class=\"juand-content juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<h2>Une symphonie de la vue et du son<\/h2>\n<p>Le d\u00e9veloppeur Enhance Games, dirig\u00e9 par l&#039;\u00e9vang\u00e9liste de la synesth\u00e9sie Tetsuya Mizuguchi (l&#039;esprit cr\u00e9atif derri\u00e8re <em>R\u00e9serve<\/em> et <em>Lumines<\/em>), a abord\u00e9 Tetris avec un objectif audacieux\u00a0: transformer chaque drop et chaque rotation en instrument d&#039;une \u0153uvre musicale vivante. Cette promesse se concr\u00e9tise d\u00e8s la premi\u00e8re ligne. Des soft-drops d\u00e9clenchent des samples de charleston al\u00e9atoires\u00a0; un T-spin rapide fait jaillir un \u00e9cho de synth\u00e9\u00a0; des Tetris multipliant les partitions d\u00e9clenchent des accords en \u00e9toile qui ondulent \u00e0 travers la palette de couleurs d&#039;une sc\u00e8ne. Le r\u00e9sultat final est moins \u00ab\u00a0un nouvel habillage de Tetris\u00a0\u00bb qu&#039;un \u00ab\u00a0concert son et lumi\u00e8re participatif\u00a0\u00bb. M\u00eame en mode portable sur un PC de poche, l&#039;exp\u00e9rience semble vivante\u00a0; branchez un bon casque ferm\u00e9 et le monde ext\u00e9rieur se dissout compl\u00e8tement.<\/p>\n<p>Le design visuel amplifie cette sensation d&#039;immersion. Un instant, vous empilez des t\u00e9trominos de n\u00e9on sous des m\u00e9duses scintillantes dans un oc\u00e9an de minuit\u00a0; l&#039;instant d&#039;apr\u00e8s, vous foncez \u00e0 travers une n\u00e9buleuse remplie de constellations, tandis que des voix chorales r\u00e9sonnent autour de vous. Des effets de particules accompagnent chaque crescendo musical, chacun \u00e9tant si parfaitement synchronis\u00e9 que l&#039;\u00e9cran semble se synchroniser avec le rythme qui palpite dans votre poitrine. C&#039;est comme si les blocs monochromes embl\u00e9matiques de 1989 avaient \u00e9volu\u00e9 pour devenir des organismes vivants et respirants.<\/p>\n<p>Le coup de gr\u00e2ce, cependant, c&#039;est la r\u00e9alit\u00e9 virtuelle. En VR, chaque \u00e9l\u00e9ment d&#039;arri\u00e8re-plan domine, conf\u00e9rant au terrain de jeu une sensation de flottement spatial que les captures d&#039;\u00e9cran ne peuvent rendre. Des nuages de lumi\u00e8re stellaire glissent si pr\u00e8s qu&#039;on a l&#039;impression de pouvoir effleurer leurs nageoires. La classique \u00ab\u00a0zone Tetris\u00a0\u00bb, o\u00f9 la vision p\u00e9riph\u00e9rique s&#039;\u00e9vanouit, devient litt\u00e9rale\u00a0: l&#039;univers tout entier se r\u00e9duit \u00e0 un puits lumineux de formes tombantes et \u00e0 une bande-son qui vous enveloppe comme de l&#039;eau chaude.<\/p>\n<h2>Mode Voyage : L&#039;album que vous jouez avec vos mains<\/h2>\n<p><em>Mode voyage<\/em> est le c\u0153ur battant du jeu\u00a0: un ensemble d&#039;une trentaine de niveaux soigneusement s\u00e9lectionn\u00e9s, assembl\u00e9s comme les pistes d&#039;un album concept \u00e9lectronique. Le rythme est r\u00e9fl\u00e9chi. Les premiers niveaux se d\u00e9roulent \u00e0 une vitesse m\u00e9ditative de 1,0, permettant aux nouveaux joueurs de s&#039;acclimater tandis que les douces m\u00e9lodies fluctuent. Une demi-heure plus tard, vous encha\u00eenez les rythmes endiabl\u00e9s, les rythmes drum and bass vous poussant vers une concentration digne d&#039;un marathonien. Pourtant, le jeu ne semble jamais brusque, car chaque transition \u2013 tempo, palette de couleurs, m\u00eame la forme de la matrice t\u00e9tromino \u2013 suit une ligne musicale.<\/p><div id=\"juand-2878281486\" class=\"juand-content_2 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Ce qui me fait revenir, cependant, c&#039;est la courbe de difficult\u00e9 dynamique du jeu. Des parties impeccables et des Tetris encha\u00een\u00e9s augmentent subtilement la v\u00e9locit\u00e9 et la complexit\u00e9, injectant des couches de percussions suppl\u00e9mentaires ou des harmonies vocales comme r\u00e9compenses sonores. Une erreur de frappe b\u00e2cl\u00e9e et la musique s&#039;amenuise, la vitesse chute et vous avez droit \u00e0 une pause. Ce syst\u00e8me de score r\u00e9actif transforme chaque partie en un remix sur mesure. Apr\u00e8s des dizaines de parties termin\u00e9es, je remarque encore de nouveaux d\u00e9tails\u00a0: une ligne de basse enfouie qui refait surface lorsque j&#039;encha\u00eene un clear parfait, une soudaine envol\u00e9e de ch\u0153ur lorsque la m\u00e9canique de Zone propulse ma ligne clear vers des sommets mythiques.<\/p>\n<p>En parlant de la <strong>Zone<\/strong>: Remplir sa jauge permet de figer le temps, de l\u00e2cher des pi\u00e8ces sans progression et d&#039;encha\u00eener les combos qui comptent apr\u00e8s le red\u00e9marrage du chrono. Au premier abord, cela ressemble \u00e0 un bouton de panique tape-\u00e0-l&#039;\u0153il, mais une strat\u00e9gie plus approfondie \u00e9merge rapidement\u00a0: utiliser Zone comme moteur de score offensif ou comme une bou\u00e9e de sauvetage de derni\u00e8re minute lors de sprints \u00e0 20\u00a0vitesses. C&#039;est l&#039;ajout m\u00e9canique le plus audacieux de la s\u00e9rie, et pourtant il s&#039;int\u00e8gre si naturellement au flux que le retour au Tetris classique semble presque aust\u00e8re.<\/p>\n<h2>Connect\u00e9 : Chaos coop\u00e9ratif et tension concurrentielle<\/h2>\n<p>Quand <em>Connect\u00e9<\/em> rejoint l&#039;original <em>Effet Tetris<\/em> En 2020, ce n&#039;\u00e9tait pas qu&#039;un sous-titre, c&#039;\u00e9tait une v\u00e9ritable mission. Ce mode coop\u00e9ratif phare \u00e0 trois joueurs vous oppose, avec deux inconnus (ou amis), \u00e0 des \u00ab\u00a0boss\u00a0\u00bb contr\u00f4l\u00e9s par l&#039;IA. Chaque joueur g\u00e8re son plateau personnel jusqu&#039;\u00e0 ce qu&#039;une jauge commune se remplisse\u00a0; vos matrices fusionnent alors pour former un immense terrain de jeu commun o\u00f9 chacun pose des blocs \u00e0 tour de r\u00f4le. Regarder trois esprits coordonner des T-Spins sur un m\u00eame plateau est grisant, et la r\u00e9compense triomphale, qui fait trembler les enceintes, lorsque vous brisez la barre de vie d&#039;un boss est ind\u00e9modable.<\/p>\n<p>Des options comp\u00e9titives \u00e9largissent encore davantage l\u2019offre. <em>Bataille de zone<\/em> Combine le combat classique en un contre un avec la m\u00e9canique de Zone qui arr\u00eate le temps, transformant les matchs en oscillations fr\u00e9n\u00e9tiques. L&#039;Attaque de Score Standard et l&#039;Attaque de Score Classique (qui d\u00e9sactive les am\u00e9liorations modernes comme la tenue de pi\u00e8ce) satisfont les puristes en qu\u00eate de records personnels. Gr\u00e2ce au code r\u00e9seau de type \u00ab\u00a0rollback\u00a0\u00bb, mes matchs transatlantiques sont rarement perturb\u00e9s\u00a0; le plus souvent, ma perte est due \u00e0 un mauvais timing, et non \u00e0 un lag.<\/p>\n<p>Le multijoueur n&#039;est pas la raison principale pour laquelle j&#039;adore <em>Effet Tetris<\/em>, mais sa pr\u00e9sence a prolong\u00e9 mon obsession. Apr\u00e8s avoir termin\u00e9 le mode Voyage en difficult\u00e9 maximale, courir apr\u00e8s la gloire du classement en Score Attack ou coordonner des nettoyages de zone avec des amis devient un nouveau d\u00e9fi.<\/p><div id=\"juand-737250040\" class=\"juand-content_3 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<h2>Musique : Le c\u0153ur battant du jeu<\/h2>\n<p>Les albums de musique de jeu font rarement partie de ma rotation Spotify, mais <em>Effet Tetris<\/em>La bande originale de est un incontournable depuis sa premi\u00e8re sortie en 2021. \u00ab Connected (Yours Forever) \u00bb superpose des voix gospel sur des rythmes house puls\u00e9s jusqu&#039;\u00e0 ce que le refrain final explose sous une pluie de clears parfaits. \u00ab Flames \u00bb marie des claquements de mains flamenco \u00e0 des riffs de guitare cyberpunk, son tempo s&#039;acc\u00e9l\u00e9rant au rythme du compteur de vitesse. Puis il y a \u00ab So They Say \u00bb, une berceuse r\u00eaveuse qui transforme un marathon habituellement effr\u00e9n\u00e9 de 150 lignes en un moment de concentration b\u00e9ate.<\/p>\n<p>Ces pistes sont avant tout interactives. La piste rythmique peut commencer avec parcimonie, mais vos rotations et vos att\u00e9nuations douces cr\u00e9ent des accents percussifs, vous propulsant en partenariat avec le compositeur. Au bout d&#039;un moment, vous cessez d&#039;\u00ab \u00e9couter \u00bb et commencez \u00e0 \u00ab jouer \u00bb, r\u00e9pondant aux signaux comme le ferait un pianiste improvisateur.<\/p>\n<h2>Performance, accessibilit\u00e9 et finition technique<\/h2>\n<p>Sous le capot, le jeu est aussi \u00e9l\u00e9gant que ses graphismes. Sur Xbox Series S et X, il maintient un 60 ips impeccable en 4K (sur la Series S, le 1440p dynamique chute rarement). Mon ordinateur portable Ryzen de milieu de gamme atteint 144 ips en 1080p sans probl\u00e8me. Le rendu VR, que ce soit via Meta Quest Link ou Valve Index, assure un rythme d&#039;images fluide, m\u00eame sous les pluies de confettis.<\/p>\n<p>Enhance int\u00e8gre \u00e9galement de nombreuses options d&#039;accessibilit\u00e9\u00a0: modes de particules \u00e0 intensit\u00e9 r\u00e9duite, palettes daltoniennes, curseurs de luminosit\u00e9 pour la photosensibilit\u00e9 et r\u00e9affectation compl\u00e8te des boutons. Pour un jeu aussi intense visuellement, ces outils permettent de r\u00e9duire consid\u00e9rablement le nombre de joueurs laiss\u00e9s pour compte, et je l&#039;ai recommand\u00e9 \u00e0 des amis qui souffrent habituellement de surcharge sensorielle.<\/p><div id=\"juand-45664594\" class=\"juand-content_4 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<h2>La sortie du Game Pass\u00a0: une porte perdue, mais une long\u00e9vit\u00e9 accrue<\/h2>\n<p>Je mentirais si je disais que la commodit\u00e9 de <em>Effet Tetris<\/em>\u00c0 l&#039;\u00e9poque du Game Pass. Discovery \u00e9tait fluide\u00a0; les amis pouvaient rejoindre le mode coop\u00e9ratif sur un coup de t\u00eate. Lorsque le partenariat a pris fin en avril 2023, des rumeurs ont surgi en ligne pour savoir si le jeu allait dispara\u00eetre sans cet abonnement. Mon exp\u00e9rience sugg\u00e8re le contraire. Certes, le nombre de joueurs a diminu\u00e9 pendant un mois, mais ceux qui sont rest\u00e9s sont des habitu\u00e9s\u00a0: des comp\u00e9titeurs de haut niveau, des \u00e9quipes de coop\u00e9ration d\u00e9vou\u00e9es et de nouveaux acheteurs qui ont mis la main sur le jeu pendant les soldes saisonni\u00e8res. Les salons continuent de se remplir aux heures de grande \u00e9coute, et les scores des classements continuent de grimper chaque semaine.<\/p>\n<p>Plus important encore, poss\u00e9der le jeu m&#039;a lib\u00e9r\u00e9 du d\u00e9sabonnement. C&#039;est devenu cet album num\u00e9rique intemporel sur mon \u00e9tag\u00e8re, comme<em>La face cach\u00e9e de la lune<\/em> ou<em>Genre de bleu<\/em>\u2014pr\u00eat d\u00e8s que l&#039;envie vous en prend, ind\u00e9pendamment des calendriers de licences.<\/p>\n<h2>Des petites chicanes dans un ensemble par ailleurs stellaire<\/h2>\n<p>Aucun chef-d&#039;\u0153uvre n&#039;est parfait, voici donc quelques points faibles :<\/p>\n<ul>\n<li><strong>Pics de difficult\u00e9 en fin de partie<\/strong>La derni\u00e8re partie du mode Voyage en mode Expert peut passer de \u00ab palpitante \u00bb \u00e0 \u00ab \u00e9prouvante \u00bb en une demi-\u00e9tape. Les d\u00e9butants peuvent rebondir sans se rendre compte qu&#039;il existe des difficult\u00e9s plus faibles.<\/li>\n<li><strong>Population connect\u00e9e en dehors des heures de pointe<\/strong>Si vous vous connectez en semaine le matin, attendez-vous \u00e0 des temps d&#039;attente occasionnels pour Score Attack ou Zone Battle. Un filtre de matchmaking multiplateforme serait utile.<\/li>\n<li><strong>\u00c9carts de progression crois\u00e9e<\/strong>Les records personnels restent cloisonn\u00e9s par plateforme, donc mes records personnels Steam n&#039;apparaissent pas sur mon profil Xbox. \u00c0 l&#039;\u00e8re des sauvegardes cloud unifi\u00e9es, c&#039;est une omission \u00e9trange.<\/li>\n<\/ul>\n<p>Pourtant, aucun de ces d\u00e9tails ne ternit l\u2019\u00e9clat de la boucle principale.<\/p><div id=\"juand-2701770057\" class=\"juand-content_5 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/Mwcf-vC6q5s?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n\n<div id=\"review\" class=\"review-wrapper wp-review-98175 wp-review-star-type wp-review-default-template wp-review-box-full-width\">\n\t\t\t<div class=\"review-heading\">\n\t\t\t<h5 class=\"review-title\">\n\t\t\t\tVerdict\n\t\t\t\t\t\t\t<\/h5>\n\t\t<\/div>\n\t\n\t\n\t\t\t<ul class=\"review-list\">\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Graphique<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Interface<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Divertissement<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Gameplay<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Caract\u00e9ristiques<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\t\n\t\t\t\t\t\t<div class=\"review-total-wrapper\">\n\t\t\t\t<span class=\"review-total-box\">5<\/span>\n\t\t\t\t<div class=\"review-star review-total\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"review-desc\">\n\t\t\t\t<p class=\"review-summary-title\"><strong>R\u00e9sum\u00e9<\/strong><\/p>\n\t\t\t\t<p>De nombreux jeux promettent de \u00ab r\u00e9inventer \u00bb un classique ; peu parviennent \u00e0 honorer l\u2019\u00e9l\u00e9gance de l\u2019original tout en l\u2019\u00e9largissant d\u2019une mani\u00e8re qui semble in\u00e9vitable avec le recul. <em>Tetris\u202fEffect:\u202fConnected<\/em> Le jeu r\u00e9ussit son num\u00e9ro d&#039;\u00e9quilibriste avec brio. La chor\u00e9graphie audiovisuelle est \u00e9poustouflante, le syst\u00e8me Zone injecte de nouvelles couches de strat\u00e9gie, et la multitude de modes captive durablement les joueurs solo comme les joueurs comp\u00e9titifs.<\/p>\n<p>Je joue \u00e0 Tetris sous une forme ou une autre depuis l&#039;enfance, et pourtant, en 2021, pour la premi\u00e8re fois, le jeu m&#039;a v\u00e9ritablement transport\u00e9, corps et esprit, vers un monde transcendant. Deux ans apr\u00e8s son adieu au Game Pass, il conserve toujours cette puissance. Que vous ayez envie d&#039;\u00e9tats de flow m\u00e9ditatifs, de sprints haletants au classement ou d&#039;une session de co-op entre amis, c&#039;est la version de Tetris qui restera install\u00e9e sur mon disque dur pour le reste de la d\u00e9cennie.<\/p>\n\t\t\t<\/div>\n\t\t\t\n\t\n\t<\/div>\n\n<style type=\"text\/css\">\n\t.wp-review-98175.review-wrapper{\n\t\twidth:100%;\n\t\toverflow:hidden;\n\t}\n\t.wp-review-98175.review-wrapper,\n\t.wp-review-98175 .review-title,\n\t.wp-review-98175 .review-desc p,\n\t.wp-review-98175 .reviewed-item p{\n\t\tcolor:#555555;\n\t}\n\t.wp-review-98175 .review-title{\n\t\tpadding-top:15px;\n\t\tfont-weight:bold;\n\t}\n\t.wp-review-98175 .review-links a{\n\t\tcolor:#f46e06;\n\t}\n\t.wp-review-98175 .review-links a:hover{\n\t\tbackground:#f46e06;\n\t\tcolor:#fff;\n\t}\n\t.wp-review-98175 .review-list li,\n\t.wp-review-98175.review-wrapper{\n\t\tbackground:#ffffff;\n\t}\n\t.wp-review-98175 .review-title,\n\t.wp-review-98175 .review-list li:nth-child(2n),\n\t.wp-review-98175 .wpr-user-features-rating .user-review-title{\n\t\tbackground:#e7e7e7;\n\t}\n\t.wp-review-98175.review-wrapper,\n\t.wp-review-98175 .review-title,\n\t.wp-review-98175 .review-list li,\n\t.wp-review-98175 .review-list li:last-child,\n\t.wp-review-98175 .user-review-area,\n\t.wp-review-98175 .reviewed-item,\n\t.wp-review-98175 .review-links,\n\t.wp-review-98175 .wpr-user-features-rating{\n\t\tborder-color:#e7e7e7;\n\t}\n\t.wp-review-98175 .wpr-rating-accept-btn{\n\t\tbackground:#f46e06;\n\t}\n\t.wp-review-98175.review-wrapper .user-review-title{\n\t\tcolor:inherit;\n\t}\n<\/style>","protected":false},"excerpt":{"rendered":"<p>J&#039;ai d\u00e9couvert Tetris Effect: Connected d\u00e9but 2021, alors qu&#039;il \u00e9tait confortablement install\u00e9 dans la biblioth\u00e8que Xbox Game Pass. \u00ab C&#039;est Tetris, comment pourrait-il \u00eatre diff\u00e9rent ? \u00bb me suis-je dit, me pr\u00e9parant \u00e0 une petite bouff\u00e9e de nostalgie avant d&#039;aller me coucher. Trois heures hypnotiques plus tard, j&#039;avais les yeux \u00e9carquill\u00e9s, casque viss\u00e9 sur les oreilles, convaincu d&#039;avoir jou\u00e9 \u00e0 la version la plus transformatrice du jeu de puzzle classique d&#039;Alexey Pajitnov depuis l&#039;\u00e8re Juan sur PlayStation.<\/p>","protected":false},"author":1,"featured_media":98184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1281,1287],"tags":[4558],"class_list":["post-98175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-reviews","tag-home"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2025\/05\/EGS_TetrisEffectConnected_MonstarsincResonairStageGames_S1_2560x1440-973b58bf2a546f41339157cfc827a6a6.jpeg?fit=2560%2C1440&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8STS8-pxt","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/98175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/comments?post=98175"}],"version-history":[{"count":3,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/98175\/revisions"}],"predecessor-version":[{"id":98186,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/98175\/revisions\/98186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/media\/98184"}],"wp:attachment":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/media?parent=98175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/categories?post=98175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/tags?post=98175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}