{"id":84730,"date":"2025-04-17T12:14:26","date_gmt":"2025-04-17T11:14:26","guid":{"rendered":"https:\/\/blog.juandesouza.com\/?p=84730"},"modified":"2025-04-18T18:41:30","modified_gmt":"2025-04-18T17:41:30","slug":"comment-linflation-reduit-votre-pouvoir-dachat-chaque-jour-et-vous-rend-plus-pauvre","status":"publish","type":"post","link":"https:\/\/blog.juandesouza.com\/fr\/finance\/comment-linflation-reduit-votre-pouvoir-dachat-chaque-jour-et-vous-rend-plus-pauvre\/","title":{"rendered":"Comment l&#039;inflation r\u00e9duit votre pouvoir d&#039;achat chaque jour et vous devenez pauvre"},"content":{"rendered":"<p>Comme je l&#039;ai mentionn\u00e9 dans d&#039;autres articles, l&#039;inflation ne se traduit pas toujours par une hausse des prix pour le consommateur, comme beaucoup l&#039;imaginent, d&#039;autant plus que la concurrence oblige les marques \u00e0 maintenir des prix bas. Dans certains cas, le produit lui-m\u00eame ne co\u00fbte pas plus cher, mais l&#039;emballage contient moins d&#039;unit\u00e9s ou des poids et dimensions plus petits qu&#039;auparavant, ce qui est pr\u00e9cis\u00e9ment le cas actuellement au Br\u00e9sil et dans le monde entier.<\/p>\n<p>En pratique, ce ph\u00e9nom\u00e8ne est connu sous le nom de \u00ab\u00a0shrinkflation\u00a0\u00bb. Il s&#039;agit d&#039;une strat\u00e9gie commerciale\u00a0: r\u00e9duire la taille du produit pour \u00e9viter d&#039;en augmenter le prix. Mais en r\u00e9alit\u00e9, cela finit par co\u00fbter plus cher au consommateur, car on obtient moins pour le m\u00eame prix. Voici une question\u00a0: ne trouvez-vous pas \u00e9trange que l&#039;argument environnemental pour \u00ab\u00a0supprimer les chargeurs des t\u00e9l\u00e9phones portables\u00a0\u00bb ne s&#039;accompagne jamais d&#039;une proposition de \u00ab\u00a0baisse du prix du produit\u00a0\u00bb\u00a0? De quoi r\u00e9fl\u00e9chir\u2026<\/p><div id=\"juand-1400842295\" class=\"juand-content juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Ici au Br\u00e9sil, des millions de Br\u00e9siliens vivent d\u00e9j\u00e0 avec une inflation cumul\u00e9e de 9,68% sur 12 mois et se plaignent de produits toujours plus petits. Par exemple, les bo\u00eetes d&#039;\u0153ufs ne contiennent plus une douzaine\u00a0; les chocolats et les biscuits ont r\u00e9tr\u00e9ci\u00a0; la lessive dure moins longtemps. Ce ne sont l\u00e0 que quelques exemples concrets de la fa\u00e7on dont les fabricants s&#039;adaptent.<\/p>\n<p>La l\u00e9gislation nationale oblige les entreprises \u00e0 annoncer toute r\u00e9duction sur l&#039;emballage. Cependant, les organismes de protection des consommateurs estiment que cet avis n&#039;est pas toujours suffisamment clair. Dans l&#039;\u00c9tat de S\u00e3o Paulo, par exemple, si l&#039;indication est trop faible, le consommateur peut exiger un remboursement int\u00e9gral. Le saviez-vous\u00a0?<\/p>\n<h2>R\u00e9duire consid\u00e9rablement la Pa\u00e7oca<\/h2>\n<p>M\u00eame la pa\u00e7oquinha, un produit br\u00e9silien tr\u00e8s appr\u00e9ci\u00e9 et d\u00e9sormais export\u00e9 dans le monde entier, n&#039;a pas \u00e9chapp\u00e9 \u00e0 l&#039;inflation. Santa Helena, l&#039;un des plus grands fabricants br\u00e9siliens, a d\u00e9clar\u00e9 \u00e0 UOL avoir r\u00e9duit de 4 g la quantit\u00e9 de ses emballages rectangulaires, y compris ceux de la marque Cuida Bem. Selon Santa Helena, cette r\u00e9duction est due \u00e0 l&#039;inflation des mati\u00e8res premi\u00e8res, le prix des arachides ayant augment\u00e9 de 501 TP6T et les co\u00fbts d&#039;emballage de 391 TP6T.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2021\/11\/blogdojuan-pacoquita.webp?ssl=1\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Infla\u00e7\u00e3o nos prix du Br\u00e9sil et du monde\" src=\"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2021\/11\/blogdojuan-pacoquita.webp?w=880&#038;ssl=1\" alt=\"L&#039;inflation vous deixando pobre. Entendez-vous !\" \/><\/a><\/div>\n<h2>Les emballages de riz et de sucre sont plus petits<\/h2>\n<p>Outre la pa\u00e7oca \u2013 et de nombreux chocolats dont le poids est pass\u00e9 de 110 g \u00e0 90 g \u2013, les gourmands ont ressenti une baisse de prix m\u00eame pour les emballages de sucre, d\u00e9sormais vendus \u00e0 moins d&#039;un kg. C&#039;est \u00e9trange et alarmant, disent de nombreux consommateurs.<\/p><div id=\"juand-1981315635\" class=\"juand-content_2 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<div>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"pt\">Outro dia, fui enganado (\ud83e\udd21) por un saco de a\u00e7\u00facar refinado. En g\u00e9n\u00e9ral, nous sommes livr\u00e9s avec des paquets de 1 kg, mais ils ont un emballage diff\u00e9rent, avec un poids diff\u00e9rent. Paguei dez centavos amenos por un saco de a\u00e7\u00facar refinado de OITOCENTOS GRAMAS. Grande \u00ab \u00e9conomie \u00bb. <a href=\"https:\/\/t.co\/2BrbyqMEJv\">pic.twitter.com\/2BrbyqMEJv<\/a><\/p>\n<p>\u2014 Thiago C. (@thiagoch8) <a href=\"https:\/\/twitter.com\/thiagoch8\/status\/1416109357130031106?ref_src=twsrc%5Etfw\">16 juillet 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n<p>Mais Juan, comment r\u00e9soudre ce probl\u00e8me\u00a0? J\u2019aimerais avoir une r\u00e9ponse simple et universelle \u00e0 un probl\u00e8me aussi vaste et complexe. Pour l\u2019instant, le plus important est d\u2019investir judicieusement votre argent, en fonction de vos moyens, afin de compenser l\u2019\u00e9cart d\u2019inflation de +10% au Br\u00e9sil. La diversification est essentielle pour \u00e9quilibrer votre portefeuille et r\u00e9duire l\u2019impact de l\u2019inflation sur votre vie ou votre entreprise.<\/p>\n<p>Et vous, qu&#039;avez-vous pens\u00e9 de cet article sur l&#039;inflation ?<\/p>\n<p>Photo de <a href=\"https:\/\/www.pexels.com\/photo\/50-euro-banknote-beside-black-calculator-221174\/\" target=\"_blank\" rel=\"noopener\">Pixabay<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme je l&#039;ai mentionn\u00e9 dans d&#039;autres articles, l&#039;inflation ne se traduit pas toujours par une hausse des prix pour le consommateur, comme beaucoup l&#039;imaginent, d&#039;autant plus que la concurrence oblige les marques \u00e0 maintenir des prix bas. Dans certains cas, le produit lui-m\u00eame ne co\u00fbte pas plus cher, mais l&#039;emballage contient moins d&#039;unit\u00e9s ou des poids et dimensions plus petits qu&#039;auparavant, ce qui est pr\u00e9cis\u00e9ment le cas actuellement au Br\u00e9sil et dans le monde entier.<\/p>","protected":false},"author":1,"featured_media":98014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1280],"tags":[],"class_list":["post-84730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finance"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2021\/11\/pexels-pixabay-221174.jpg?fit=1920%2C1280&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8STS8-m2C","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/84730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/comments?post=84730"}],"version-history":[{"count":4,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/84730\/revisions"}],"predecessor-version":[{"id":98017,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/84730\/revisions\/98017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/media\/98014"}],"wp:attachment":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/media?parent=84730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/categories?post=84730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/tags?post=84730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}