{"id":82352,"date":"2015-05-26T11:26:27","date_gmt":"2015-05-26T14:26:27","guid":{"rendered":"http:\/\/3.238.148.255\/?p=82352"},"modified":"2025-04-14T17:14:06","modified_gmt":"2025-04-14T16:14:06","slug":"review-dragon-age-inquisition","status":"publish","type":"post","link":"https:\/\/blog.juandesouza.com\/fr\/games\/review-dragon-age-inquisition\/","title":{"rendered":"Review: Dragon Age: Inquisition"},"content":{"rendered":"<p>Dragon Age\u00a0: Inquisition est le dernier chapitre de la franchise RPG traditionnelle de BioWare, d\u00e9veloppeur canadien \u00e9galement \u00e0 l&#039;origine de la trilogie Mass Effect. Disponible sur PlayStation 4, PlayStation 3, Xbox One, Xbox 360 et PC, Inquisition figurait sur la liste des jeux incontournables de la plupart des joueurs avant sa sortie. D\u00e9couvrez mon test complet ci-dessous\u00a0!<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img1.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Dragon Age: Inquisition\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img1-e1432674297277.jpg?w=880&#038;ssl=1\" alt=\"Analyse de Dragon Age Inquisition sur PC\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Source de l&#039;image : <a href=\"http:\/\/www.dragonage.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">EA Games<\/a><\/div>\n<\/p>\n<p>Le jeu raconte une histoire qui revisite certains \u00e9v\u00e9nements du deuxi\u00e8me volet de la franchise. Le continent de Th\u00e9das, situ\u00e9 dans un d\u00e9cor peu accueillant, est loin d&#039;\u00eatre accueillant. Au c\u0153ur des relations troubles entre mages et templiers, une myst\u00e9rieuse explosion magique a cr\u00e9\u00e9 une fissure immat\u00e9rielle astronomique, capable de lib\u00e9rer cr\u00e9atures mal\u00e9fiques et d\u00e9mons dans les r\u00e9gions de F\u00e9relden et d&#039;Orla\u00efs.<\/p><div id=\"juand-2665281981\" class=\"juand-content juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Cet \u00e9v\u00e9nement a d\u00e9truit des villes et co\u00fbt\u00e9 la vie \u00e0 des milliers de personnes dans la r\u00e9gion. Votre personnage est devenu le seul survivant, quelqu&#039;un qui ne comprenait pas vraiment comment tout cela s&#039;\u00e9tait pass\u00e9, mais qui a \u00e9t\u00e9 retrouv\u00e9 vivant.<\/p>\n<div style=\"width: 100%\"><iframe loading=\"lazy\" width=\"100%\" height=\"500\" src=\"https:\/\/www.youtube.com\/embed\/pZ8MV-SI-DY\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<p>Aux c\u00f4t\u00e9s d&#039;autres guerriers, le protagoniste (votre personnage) a fond\u00e9 l&#039;Inquisition, un ordre d\u00e9termin\u00e9 \u00e0 colmater d\u00e9finitivement toutes les br\u00e8ches mal\u00e9fiques et \u00e0 r\u00e9tablir la paix \u00e0 Th\u00e9das. Au d\u00e9but de l&#039;histoire, le seul survivant et chef supr\u00eame de l&#039;Inquisition se voit d\u00e9cerner une myst\u00e9rieuse cicatrice sur la main, dont le pouvoir est capable de sceller divers portails.<\/p>\n<p>Fid\u00e8le \u00e0 la tradition de BioWare, vous devrez faire face \u00e0 une grande vari\u00e9t\u00e9 d&#039;\u00e9v\u00e9nements en mode campagne. Cela signifie \u00e9galement que les dialogues offrent toujours de multiples options de r\u00e9ponse, vous obligeant \u00e0 choisir l&#039;avenir de l&#039;humanit\u00e9 locale. Gardez \u00e0 l&#039;esprit que certains choix peuvent influencer directement l&#039;issue de l&#039;histoire, et c&#039;est \u00e0 vous de d\u00e9cider qui survivra.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img2.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Dragon Age: Inquisition\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img2-e1432674736297.jpg?w=880&#038;ssl=1\" alt=\"Dragon Age Inquisition sur Xbox One\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Source de l&#039;image : <a href=\"http:\/\/www.dragonage.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">EA Games<\/a><\/div>\n<\/p>\n<p>Dans Dragon Age : Inquisition, vous pouvez personnaliser votre protagoniste exactement comme vous le souhaitez, avec la possibilit\u00e9 de choisir exclusivement parmi l&#039;une des quatre races disponibles : <b>Humain<\/b>, <b>Nain<\/b>, <b>Elfe<\/b>, et <b>Qunari<\/b>De plus, le syst\u00e8me de personnalisation du jeu vous permet de configurer les moindres d\u00e9tails de votre personnage, tels que les marques d&#039;expression faciale, les tatouages faciaux et m\u00eame le degr\u00e9 de pro\u00e9minence du visage.<\/p><div id=\"juand-2100929537\" class=\"juand-content_2 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Autrement dit, votre personnage et votre groupe de guerriers sont enti\u00e8rement personnalisables \u00e0 votre go\u00fbt, rendant le gameplay encore plus captivant. Comme dans les autres jeux de la franchise, Inquisition vous offre la libert\u00e9 de choisir les combattants de votre groupe. Chaque personnage secondaire poss\u00e8de des attributs de combat exclusifs, et votre choix d\u00e9pend de la strat\u00e9gie que vous adoptez.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img3.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Dragon Age: Inquisition\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img3-e1432674978251.jpg?w=880&#038;ssl=1\" alt=\"Dragon Age Inquisition sur Xbox One\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Source de l&#039;image : <a href=\"http:\/\/www.dragonage.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">EA Games<\/a><\/div>\n<\/p>\n<p>Le voleur habile <b>T\u00e9thras varrique<\/b> de Dragon Age 2 revient avec ses techniques de tir \u00e0 l&#039;arc am\u00e9lior\u00e9es. Outre lui, d&#039;autres personnages m\u00e9morables peuvent rejoindre votre escouade, comme <b>Cassandra Pentaghast<\/b>\u2014un guerrier imp\u00e9tueux et noble\u2014 ainsi que d\u2019autres sp\u00e9cialistes du combat.<\/p>\n<p>Dragon Age: Inquisition offre l&#039;un des univers les plus immersifs des RPG actuels. Au d\u00e9but de votre aventure, le jeu d\u00e9marre calmement, avec un tutoriel tr\u00e8s lin\u00e9aire. Cependant, une fois l&#039;exploration de Th\u00e9das d\u00e9bloqu\u00e9e, d&#039;innombrables activit\u00e9s appara\u00eetront pour vous captiver et, bien s\u00fbr, vous occuper pendant un long moment.<\/p>\n<p>Un aspect extr\u00eamement positif d&#039;Inquisition est la sensation d&#039;\u00eatre perdu dans sa carte gigantesque. Comment cela ? Se sentir perdu dans Inquisition vous garantit d&#039;avoir toujours des t\u00e2ches de toutes sortes et de tous styles \u00e0 accomplir. Le jeu vous poussera \u00e9galement \u00e0 chasser des monstres, des dragons et des soldats rivaux, car la mont\u00e9e en niveau est consid\u00e9r\u00e9e comme une n\u00e9cessit\u00e9.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img4.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Dragon Age: Inquisition\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img4-e1432675653906.jpg?w=880&#038;ssl=1\" alt=\"Dragon Age Inquisition sur PlayStation\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Source de l&#039;image : <a href=\"http:\/\/www.dragonage.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">EA Games<\/a><\/div>\n<\/p>\n<p>Nous pouvons avertir d&#039;avance que les joueurs moins familiers avec la franchise pourraient avoir du mal \u00e0 assimiler la richesse d&#039;informations offerte par l&#039;univers de Dragon Age. De plus, les joueurs novices pourraient \u00eatre intimid\u00e9s par le syst\u00e8me d&#039;am\u00e9lioration complet des armes, des comp\u00e9tences et des armures. La grande vari\u00e9t\u00e9 d&#039;objets et d&#039;accessoires permettant de g\u00e9n\u00e9rer de nouveaux \u00e9quipements est impressionnante.<\/p><div id=\"juand-2289125815\" class=\"juand-content_3 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Les environnements regorgent de composants, de plantes, de coffres, de notes et d&#039;objets de valeur. Le nombre de missions dans Dragon Age\u00a0: Inquisition est exorbitant. Contrairement aux grands jeux en monde ouvert, Inquisition est divis\u00e9 en plusieurs zones. Cependant, nombre de ces zones sont suffisamment vastes pour occuper tout votre temps libre. Croyez-le ou non, Dragon Age\u00a0: Inquisition est un jeu bien plus vaste qu&#039;il n&#039;y para\u00eet.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img9.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Dragon Age: Inquisition\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img9-e1432676135743.jpg?w=880&#038;ssl=1\" alt=\"Test d&#039;Inquisition de Dragon Age\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Source de l&#039;image : <a href=\"http:\/\/www.dragonage.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">EA Games<\/a><\/div>\n<\/p>\n<p>C\u00f4t\u00e9 gameplay, le jeu propose les combats les plus dynamiques jamais vus. La possibilit\u00e9 de verrouiller des ennemis sp\u00e9cifiques est sans aucun doute tr\u00e8s utile lors des combats difficiles, m\u00eame si elle est parfois impr\u00e9cise, tout comme la cam\u00e9ra d\u00e9sorient\u00e9e qui vous d\u00e9savantage souvent lors des affrontements en espaces confin\u00e9s.<\/p>\n<p>Globalement, le syst\u00e8me de combat fonctionne tr\u00e8s bien\u00a0; en maintenant simplement certains boutons enfonc\u00e9s, vous pouvez ex\u00e9cuter des attaques de base et des comp\u00e9tences sp\u00e9ciales. En plus des actions d\u00e9j\u00e0 famili\u00e8res aux fans de la franchise, votre personnage est d\u00e9sormais capable de sauter pour atteindre des zones difficiles d&#039;acc\u00e8s.<\/p>\n<p>Une perspective plus strat\u00e9gique permet au joueur de diriger les actions de son personnage au fil des tours, d&#039;un simple bouton. Si la vue tactique du plateau n&#039;est pas obligatoire, elle devient indispensable aux niveaux sup\u00e9rieurs, notamment gr\u00e2ce \u00e0 la possibilit\u00e9 de mettre le temps en pause.<\/p><div id=\"juand-2610172139\" class=\"juand-content_4 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img5.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Dragon Age: Inquisition\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img8-e1432676034748.jpg?w=880&#038;ssl=1\" alt=\"Dragon Age Inquisition Review\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Source de l&#039;image : <a href=\"http:\/\/www.dragonage.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">EA Games<\/a><\/div>\n<\/p>\n<p>Dragon Age\u00a0: Inquisition propose \u00e9galement un mode multijoueur performant. Le mode coop\u00e9ratif est d\u00e9sormais con\u00e7u pour accueillir jusqu&#039;\u00e0 quatre joueurs, qui pourront d\u00e9couvrir des tr\u00e9sors et affronter des hordes d&#039;ennemis dans des niveaux g\u00e9n\u00e9r\u00e9s al\u00e9atoirement.<\/p>\n<p>La dynamique multijoueur n&#039;est pas particuli\u00e8rement innovante et diff\u00e8re sensiblement de l&#039;exp\u00e9rience du mode campagne, certes, mais elle reste n\u00e9anmoins divertissante. Il est \u00e0 noter que vous ne pourrez pas utiliser le m\u00eame personnage que dans l&#039;histoire principale, ce qui pourrait d\u00e9courager certains joueurs.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img9.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Dragon Age: Inquisition\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/05\/tfx-dragon-age-inquisition_img10-e1432676326882.jpg?w=880&#038;ssl=1\" alt=\"Dragon Age Inquisition Review\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Source de l&#039;image : <a href=\"http:\/\/www.dragonage.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">EA Games<\/a><\/div>\n<\/p>\n<p>Au cours de notre partie, nous avons trouv\u00e9 l&#039;exploration dans Dragon Age: Inquisition bien plus agr\u00e9able gr\u00e2ce \u00e0 ses graphismes et ses environnements \u00e9poustouflants. Les ambiances ont \u00e9t\u00e9 soigneusement con\u00e7ues pour vous captiver dans un univers fantastique regorgeant de secrets, de personnages et d&#039;activit\u00e9s m\u00e9morables. De plus, le niveau de d\u00e9tail des environnements est impressionnant\u00a0: tout semble vivant et r\u00e9el.<\/p>\n<p>Les effets de lumi\u00e8re m\u00e9ritent d&#039;\u00eatre salu\u00e9s, tout comme le travail de BioWare pour d\u00e9velopper des r\u00e9gions vari\u00e9es et riches en d\u00e9tails int\u00e9ressants. Pendant les combats, des capacit\u00e9s sp\u00e9ciales illuminent les marais, les for\u00eats, les plages et les lacs de couleurs vives et \u00e9clatantes (litt\u00e9ralement).<\/p><div id=\"juand-1756892348\" class=\"juand-content_5 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<div style=\"width: 100%\"><iframe loading=\"lazy\" width=\"100%\" height=\"500\" src=\"https:\/\/www.youtube.com\/embed\/dqLrkmhyHN4\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<p>C\u00f4t\u00e9 bande-son, Dragon Age\u00a0: Inquisition propose une musique cin\u00e9matographique, orchestrale et charg\u00e9e d&#039;\u00e9motion, comme tir\u00e9e directement d&#039;un film bas\u00e9 sur des contes traditionnels de Tolkien. Globalement, la bande-son rend le voyage encore plus \u00e9pique.<\/p>\n<p>Comme tout jeu en monde ouvert, Dragon Age: Inquisition n&#039;est pas exempt de bugs. D&#039;autres joueurs ont signal\u00e9 divers probl\u00e8mes, comme le fait que le personnage, apr\u00e8s avoir mont\u00e9 \u00e0 cheval, soit soudainement projet\u00e9 dans les airs. Malgr\u00e9 quelques probl\u00e8mes mineurs, il est certain qu&#039;ils seront r\u00e9solus lors de futures mises \u00e0 jour.<\/p>\n\n<div id=\"review\" class=\"review-wrapper wp-review-82352 wp-review-star-type wp-review-default-template wp-review-box-full-width\">\n\t\t\t<div class=\"review-heading\">\n\t\t\t<h5 class=\"review-title\">\n\t\t\t\tVerdict\n\t\t\t\t\t\t\t<\/h5>\n\t\t<\/div>\n\t\n\t\n\t\t\t<ul class=\"review-list\">\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:80%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Graphique<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:70%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Interface<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Divertissement<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Gameplay<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:80%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Caract\u00e9ristiques<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\t\n\t\t\t\t\t\t<div class=\"review-total-wrapper\">\n\t\t\t\t<span class=\"review-total-box\">4.1<\/span>\n\t\t\t\t<div class=\"review-star review-total\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:82%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"review-desc\">\n\t\t\t\t<p class=\"review-summary-title\"><strong>R\u00e9sum\u00e9<\/strong><\/p>\n\t\t\t\t<p>Dragon Age\u00a0: Inquisition est l&#039;un des RPG les plus complexes et divertissants de ces derniers temps. L&#039;aventure authentique de l&#039;Inquisition peut para\u00eetre excessivement immersive pour ceux qui recherchent une exp\u00e9rience plus accessible et, par cons\u00e9quent, superficielle. Cependant, c&#039;est une aventure incontournable pour les joueurs souhaitant passer de longues heures dans un jeu riche en contenu et, logiquement, tr\u00e8s captivant.<\/p>\n\t\t\t<\/div>\n\t\t\t\n\t\n\t<\/div>\n\n<style type=\"text\/css\">\n\t.wp-review-82352.review-wrapper{\n\t\twidth:100%;\n\t\toverflow:hidden;\n\t}\n\t.wp-review-82352.review-wrapper,\n\t.wp-review-82352 .review-title,\n\t.wp-review-82352 .review-desc p,\n\t.wp-review-82352 .reviewed-item p{\n\t\tcolor:#555555;\n\t}\n\t.wp-review-82352 .review-title{\n\t\tpadding-top:15px;\n\t\tfont-weight:bold;\n\t}\n\t.wp-review-82352 .review-links a{\n\t\tcolor:#f46e06;\n\t}\n\t.wp-review-82352 .review-links a:hover{\n\t\tbackground:#f46e06;\n\t\tcolor:#fff;\n\t}\n\t.wp-review-82352 .review-list li,\n\t.wp-review-82352.review-wrapper{\n\t\tbackground:#ffffff;\n\t}\n\t.wp-review-82352 .review-title,\n\t.wp-review-82352 .review-list li:nth-child(2n),\n\t.wp-review-82352 .wpr-user-features-rating .user-review-title{\n\t\tbackground:#e7e7e7;\n\t}\n\t.wp-review-82352.review-wrapper,\n\t.wp-review-82352 .review-title,\n\t.wp-review-82352 .review-list li,\n\t.wp-review-82352 .review-list li:last-child,\n\t.wp-review-82352 .user-review-area,\n\t.wp-review-82352 .reviewed-item,\n\t.wp-review-82352 .review-links,\n\t.wp-review-82352 .wpr-user-features-rating{\n\t\tborder-color:#e7e7e7;\n\t}\n\t.wp-review-82352 .wpr-rating-accept-btn{\n\t\tbackground:#f46e06;\n\t}\n\t.wp-review-82352.review-wrapper .user-review-title{\n\t\tcolor:inherit;\n\t}\n<\/style>\n\n<p>Et que pensez-vous de Dragon Age : Inquisition ?<\/p>","protected":false},"excerpt":{"rendered":"<p>Dragon Age\u00a0: Inquisition est le dernier volet de la franchise RPG traditionnelle de BioWare, d\u00e9veloppeur canadien \u00e9galement \u00e0 l&#039;origine de la trilogie Mass Effect. Disponible sur PlayStation 4, PlayStation 3, Xbox One, Xbox 360 et PC, Inquisition figurait sur la liste des jeux incontournables de la plupart des joueurs avant sa sortie. D\u00e9couvrez mon test complet\u00a0!<\/p>","protected":false},"author":1,"featured_media":82354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1281,1287],"tags":[],"class_list":["post-82352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-reviews"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2019\/10\/tfx-dragon-age-inquisition_img5.jpg?fit=1920%2C1080&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8STS8-lqg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/82352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/comments?post=82352"}],"version-history":[{"count":3,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/82352\/revisions"}],"predecessor-version":[{"id":97827,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/82352\/revisions\/97827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/media\/82354"}],"wp:attachment":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/media?parent=82352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/categories?post=82352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/tags?post=82352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}