{"id":82122,"date":"2017-06-21T09:30:00","date_gmt":"2017-06-21T12:30:00","guid":{"rendered":"https:\/\/www.tfxbrasil.com\/?p=24024"},"modified":"2025-04-19T03:23:39","modified_gmt":"2025-04-19T02:23:39","slug":"nostalgie-pic-vert","status":"publish","type":"post","link":"https:\/\/blog.juandesouza.com\/fr\/cinema\/nostalgie-pic-vert\/","title":{"rendered":"Nostalgie : Woody Woodpecker"},"content":{"rendered":"<p>Woody Woodpecker, l&#039;un des personnages les plus appr\u00e9ci\u00e9s de tous les temps. Ador\u00e9 des enfants, des adolescents et des adultes, le spectacle remonte \u00e0 1940. Il a \u00e9t\u00e9 cr\u00e9\u00e9 par nul autre que <strong>Walter Lantz<\/strong>Professionnel respect\u00e9, il est \u00e9galement responsable d&#039;une vaste s\u00e9rie de personnages, parmi lesquels : <strong>Buse<\/strong>, <strong>Willy le frileux<\/strong>, et <strong>L\u00e9oncio<\/strong>. \u201c<strong>Woody Woodpecker<\/strong>\u00ab\u00a0\u00c0 leur tour, ils allaient prendre diff\u00e9rentes formes. Nombre d&#039;entre elles \u00e9taient consid\u00e9r\u00e9es comme grotesques ou d\u00e9form\u00e9es \u00e0 l&#039;\u00e9poque. Ce sc\u00e9nario, soit dit en passant, ne pouvait que changer. <strong>en 1957<\/strong>. <\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2017\/05\/tfx-nostalgia-desenho-pica-pau-img2.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Woody Woodpecker\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2017\/05\/tfx-nostalgia-desenho-pica-pau-img2.jpg?fit=880%2C680&#038;ssl=1\" alt=\"Nostalgie de Woody Woodpecker\" width=\"880\" height=\"680\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Image\/Reproduction : <a href=\"http:\/\/www.imdb.com\/title\/tt0184175\/\" target=\"_blank\" rel=\"noopener noreferrer\">IMDb<\/a><\/div>\n<\/p>\n<p>Au fil des ans, son succ\u00e8s s&#039;est accru, notamment aupr\u00e8s de diff\u00e9rents publics \u00e0 travers le monde. Au Br\u00e9sil, l&#039;\u00e9mission a \u00e9t\u00e9 diffus\u00e9e par diff\u00e9rentes cha\u00eenes. Parmi elles\u00a0: <strong>TV Tupi<\/strong>, <strong>Globo<\/strong>, <strong>SBT<\/strong>, et <strong>Fox Kids<\/strong>. Actuellement, il est diffus\u00e9 via <strong>R\u00e9tablir l&#039;enregistrement<\/strong>Sur cette cha\u00eene, elle a atteint des audiences \u00e9lev\u00e9es, d\u00e9passant souvent les deux chiffres sur Ibope.<\/p><div id=\"juand-3958383384\" class=\"juand-content juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Le personnage lui-m\u00eame est bas\u00e9 sur une histoire authentique. Dans cette histoire, <strong>Walter Lantz<\/strong> a \u00e9t\u00e9 \u00ab tourment\u00e9 \u00bb pendant sa lune de miel. Dans cette histoire, un <u>pic<\/u> apparut, picorant le toit de la cabane o\u00f9 l&#039;animateur avait s\u00e9journ\u00e9. Son rire caract\u00e9ristique, quant \u00e0 lui, est une cr\u00e9ation de Mel Blanc. Il est l&#039;un des doubleurs les plus respect\u00e9s des \u00c9tats-Unis.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2017\/05\/tfx-nostalgia-desenho-pica-pau-img3.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Woody Woodpecker\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2017\/05\/tfx-nostalgia-desenho-pica-pau-img3.jpg?fit=880%2C680&#038;ssl=1\" alt=\"Nostalgie de Woody Woodpecker\" width=\"880\" height=\"680\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Image\/Reproduction : <a href=\"http:\/\/www.imdb.com\/title\/tt0184175\/\" target=\"_blank\" rel=\"noopener noreferrer\">IMDb<\/a><\/div>\n<\/p>\n<p>En parlant de doublage, plusieurs professionnels ont \u00e9t\u00e9 responsables de <strong>sa voix au Br\u00e9sil<\/strong>. Parmi les principaux : <strong>Olney Cazarr\u00e9<\/strong>, <strong>Garcia J\u00fanior<\/strong>, et <strong>Marco Ant\u00f4nio Costa<\/strong>Au Br\u00e9sil, diff\u00e9rents slogans ont \u00e9t\u00e9 cr\u00e9\u00e9s. Parmi les plus connus\u00a0: \u00ab\u00a0<strong>Vudu est pour Jacu<\/strong>&quot; et &quot;<strong>On y va<\/strong>Outre la t\u00e9l\u00e9vision, le personnage a \u00e9galement gagn\u00e9 en notori\u00e9t\u00e9 dans d&#039;autres m\u00e9dias. Au cin\u00e9ma, par exemple, avec ses nominations aux trois Oscars de 1943, 1947 et 1948. Dans les jeux vid\u00e9o, sa pr\u00e9sence croissante, devenue le th\u00e8me de plusieurs sorties pour <strong>Game Cube<\/strong>, <strong>Game Boy<\/strong>, <strong>PlayStation<\/strong>, et <strong>Syst\u00e8me ma\u00eetre<\/strong>.<br \/>\n<\/p>\n<p>Vous vous souvenez de cette \u00e9mission classique ? \ud83d\ude42<\/p>\n<p><b>Source:<\/b> <a href=\"http:\/\/woodywoodpecker.wikia.com\/wiki\/The_Woody_Woodpecker_Wiki\" target=\"_blank\" rel=\"noopener noreferrer\">Wikia<\/a><br \/>\n<b>Image:<\/b> <a href=\"http:\/\/www.imdb.com\/title\/tt0184175\/\" target=\"_blank\" rel=\"noopener noreferrer\">IMDb<\/a><\/p><div id=\"juand-1171034890\" class=\"juand-content_2 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>Woody Woodpecker, l&#039;un des personnages les plus appr\u00e9ci\u00e9s de tous les temps, ador\u00e9 des enfants, des adolescents et des adultes. La s\u00e9rie remonte \u00e0 1940. Elle a \u00e9t\u00e9 cr\u00e9\u00e9e par nul autre que Walter Lantz. Professionnel respect\u00e9, il est \u00e9galement \u00e0 l&#039;origine d&#039;une longue s\u00e9rie de personnages, dont Buzzard, Chilly Willy et Le\u00f3ncio.<\/p>","protected":false},"author":1,"featured_media":82205,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1277,1284],"tags":[],"class_list":["post-82122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinema","category-others"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2017\/06\/tfx-nostalgia-desenho-pica-pau-img1.jpg?fit=2000%2C1333&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8STS8-lmy","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/82122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/comments?post=82122"}],"version-history":[{"count":3,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/82122\/revisions"}],"predecessor-version":[{"id":98114,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/posts\/82122\/revisions\/98114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/media\/82205"}],"wp:attachment":[{"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/media?parent=82122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/categories?post=82122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/fr\/wp-json\/wp\/v2\/tags?post=82122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}