{"id":97060,"date":"2025-03-21T19:44:38","date_gmt":"2025-03-21T19:44:38","guid":{"rendered":"https:\/\/blog.juandesouza.com\/podcast\/podcast-44-keystone-o-novo-potencial-console-semelhante-ao-chromecast-sera-que-vai-dar-certo\/"},"modified":"2025-03-21T21:03:06","modified_gmt":"2025-03-21T21:03:06","slug":"podcast-44-keystone-la-nueva-consola-potencial-similar-al-chromecast-sera-que-vai-dar-certo","status":"publish","type":"post","link":"https:\/\/blog.juandesouza.com\/es\/destacado\/podcast-44-keystone-la-nueva-consola-potencial-similar-al-chromecast-sera-que-vai-dar-certo\/","title":{"rendered":"Podcast #44: Keystone, la nueva consola potencial similar a Chromecast. \u00bfFuncionar\u00e1?"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Rp-ELsEmuJ0\" width=\"580\" height=\"385\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Con el lanzamiento de nuevos productos y servicios, es relativamente com\u00fan que las grandes empresas utilicen nombres en c\u00f3digo para sus proyectos para evitar revelar demasiado demasiado pronto.<\/p>\n<p>En el caso de Microsoft, la Xbox One se llamaba en clave &quot;Durango&quot; y la Xbox Series X &quot;Project Scarlett&quot; en aquel momento. Esta vez, es posible que se haya filtrado el nombre temporal de un posible nuevo producto.<\/p><div id=\"juand-127133865\" class=\"juand-content juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Un conocido experto en tecnolog\u00eda, Tero Alhonen, revel\u00f3 en su cuenta personal de Twitter que encontr\u00f3 un c\u00f3digo de Microsoft llamado \u201cXbox Keystone\u201d.<\/p>\n<p>Esto sigue directamente despu\u00e9s de las referencias a Xbox Durango y Xbox Scarlett.<\/p>\n<p>Muchos rumores han circulado en el mercado gaming desde hace un tiempo, y todo apunta a que el nuevo producto ser\u00e1 un dispositivo tipo \u201cChromecast\u201d de Microsoft con el mando de Xbox Series, orientado a democratizar el acceso al cat\u00e1logo de Xbox con una baja inversi\u00f3n y un excelente costo-beneficio.<\/p>\n<p>\u00a1Comp\u00e1rtelo con tus amigos! \ud83d\ude42<\/p><div id=\"juand-1026242654\" class=\"juand-content_2 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=Rp-ELsEmuJ0\">Check it out on my YouTube Channel!<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>With the release of new products and services, it\u2019s relatively common for big companies to use code names for their projects to avoid revealing too much too soon. In the case of Microsoft, the Xbox One was codenamed &#8220;Durango&#8221; and the Xbox Series X was called &#8220;Project Scarlett&#8221; at the time. This time, the temporary [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":97061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2025\/03\/1742584958_maxresdefault.jpg?fit=1280%2C720&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8STS8-pfu","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/posts\/97060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/comments?post=97060"}],"version-history":[{"count":4,"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/posts\/97060\/revisions"}],"predecessor-version":[{"id":97130,"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/posts\/97060\/revisions\/97130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/media\/97061"}],"wp:attachment":[{"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/media?parent=97060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/categories?post=97060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/es\/wp-json\/wp\/v2\/tags?post=97060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}