{"id":82620,"date":"2016-03-25T20:56:34","date_gmt":"2016-03-25T23:56:34","guid":{"rendered":"http:\/\/3.238.148.255\/?p=82620"},"modified":"2025-04-19T02:15:17","modified_gmt":"2025-04-19T01:15:17","slug":"review-fallout-4","status":"publish","type":"post","link":"https:\/\/blog.juandesouza.com\/de\/games\/review-fallout-4\/","title":{"rendered":"Review: Fallout 4"},"content":{"rendered":"<p>\u201eFallout 4\u201c ist der neueste Teil der beliebten Franchise und ist f\u00fcr PlayStation 4, Xbox One und PC erh\u00e4ltlich. Entwickelt von <a href=\"https:\/\/bethesda.net\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bethesda<\/a>\u2013 das Studio hinter Skyrim \u2013 bleibt der klassischen Formel der Serie treu, verleiht ihr aber mehr \u201eFeinschliff\u201c, um das Gef\u00fchl von Freiheit im \u00d6dland zu verst\u00e4rken. Lesen Sie weiter f\u00fcr meine vollst\u00e4ndige Rezension und finden Sie heraus, ob sich der Kauf lohnt!<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2016\/03\/tfx-analise-fallout-4_img1.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2016\/03\/tfx-analise-fallout-4_img1.jpg?w=880&#038;ssl=1\" alt=\"Fallout 4 Review\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bild\/Mit freundlicher Genehmigung: <a href=\"https:\/\/www.playstation.com\/pt-br\/games\/fallout-4-ps4\/\" target=\"_blank\" rel=\"noopener noreferrer\">PlayStation<\/a><\/div>\n<\/p>\n<p>Fallout 4 erinnert Sie von Anfang an daran, dass \u201eKrieg sich nie \u00e4ndert\u201c. Dieses neue Kapitel kommt Bethesda-Fans sofort bekannt vor und l\u00e4sst Sie in eine Geschichte eintauchen, die die katastrophalen Fehler der Menschheit w\u00e4hrend stundenlanger Erkundungen in nahezu menschenleeren Landschaften widerspiegelt. <\/p><div id=\"juand-2005744752\" class=\"juand-content juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Das Spiel beginnt im Boston der Vorapokalypse \u2013 einer retro-futuristischen Mischung aus 50er-Jahre-Charme und modernster Technologie \u2013 wo ein friedliches Familientreffen durch eine nukleare Verw\u00fcstung j\u00e4h zerst\u00f6rt wird. Du spielst den einzigen \u00dcberlebenden von Vault 111 und tauchst Jahre sp\u00e4ter in eine strahlenzerst\u00f6rte Welt voller Mutanten und der besten und schlechtesten Seiten der Menschheit ein. Von diesem Moment an kannst du deinen eigenen Weg durch das Commonwealth gehen. <\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2016\/03\/tfx-analise-fallout-4_img2.png?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2016\/03\/tfx-analise-fallout-4_img2.png?w=880&#038;ssl=1\" alt=\"Fallout 4 Review\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bild\/Mit freundlicher Genehmigung: <a href=\"https:\/\/www.playstation.com\/pt-br\/games\/fallout-4-ps4\/\" target=\"_blank\" rel=\"noopener noreferrer\">PlayStation<\/a><\/div>\n<\/p>\n<p>Eines der gr\u00f6\u00dften Highlights von Fallout 4 ist die weitl\u00e4ufige offene Welt. Au\u00dferhalb von Vault 111 k\u00f6nnen Sie frei erkunden, mit minimalen Einschr\u00e4nkungen und unz\u00e4hligen Nebenaktivit\u00e4ten \u00fcber die Hauptquest hinaus \u2013 was dem Erlebnis eine willkommene Spontaneit\u00e4t verleiht. <\/p>\n<p>Die Geschichte entfaltet sich fragmentarisch, und wie gewohnt h\u00e4ngt vieles davon ab, was du daraus machst, wenn du neue Orte entdeckst und \u00dcberlebende triffst. Das Dialograd, das die Erz\u00e4hlung vorantreiben soll, kann sich jedoch eingeschr\u00e4nkt anf\u00fchlen und bietet nur wenige allgemeine Antworten. Der nat\u00fcrliche Ablauf der Ereignisse gleicht dies jedoch oft aus und l\u00e4sst dich die Auswirkungen deiner Entscheidungen deutlich erkennen. <\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2016\/03\/tfx-analise-fallout-4_img3.png?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2016\/03\/tfx-analise-fallout-4_img3.png?w=880&#038;ssl=1\" alt=\"Fallout 4 Review\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bild\/Mit freundlicher Genehmigung: <a href=\"https:\/\/www.playstation.com\/pt-br\/games\/fallout-4-ps4\/\" target=\"_blank\" rel=\"noopener noreferrer\">PlayStation<\/a><\/div>\n<\/p>\n<p>Der Kampf in Fallout 4 wirkt dank hervorragender Neuerungen noch raffinierter \u2013 vor allem dank der vollst\u00e4ndigen Anpassungsm\u00f6glichkeiten sowohl Ihrer Ausr\u00fcstung als auch Ihrer Power Armor. Alles wird aus Schrott und Materialien hergestellt, die Sie auf der Karte finden. Selbst der kleinste Schmuck kann sich also als n\u00fctzlich erweisen, anstatt nur Ihr Inventar zu \u00fcberladen. <\/p><div id=\"juand-3980980154\" class=\"juand-content_2 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Das Charaktererstellungstool bietet beispiellose Flexibilit\u00e4t, \u00e4hnlich wie bei \u201eDie Sims\u201c. Sie k\u00f6nnen jedes Gesichtsmerkmal anpassen, Narben, Sch\u00f6nheitsfehler und mehr hinzuf\u00fcgen. Obwohl die Gesichter deutlich \u00fcberarbeitet wurden, weisen die K\u00f6rpermodelle leider immer noch die f\u00fcr Bethesda typischen, ungew\u00f6hnlichen Proportionen auf. <\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2016\/03\/tfx-analise-fallout-4_img4.png?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2016\/03\/tfx-analise-fallout-4_img4.png?w=880&#038;ssl=1\" alt=\"Fallout 4 Review\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bild\/Mit freundlicher Genehmigung: <a href=\"https:\/\/www.playstation.com\/pt-br\/games\/fallout-4-ps4\/\" target=\"_blank\" rel=\"noopener noreferrer\">PlayStation<\/a><\/div>\n<\/p>\n<p>Visuell beeindruckt Fallout 4 mit einer lebendigen Welt, deren Umgebungen sich im Laufe der Zeit weiterentwickeln. Trotz dieser detaillierten Landschaften haben sich die Charakter- und NPC-Texturen seit Fallout 3 nicht wesentlich weiterentwickelt. Insgesamt ist es ein sch\u00f6nes Spiel, aber angesichts der heutigen Hardware w\u00fcnscht man sich etwas mehr Feinschliff. <\/p>\n<p>Ein gro\u00dfer Vorteil ist die vollst\u00e4ndige portugiesische Lokalisierung \u2013 Men\u00fcs, Untertitel und Benutzeroberfl\u00e4che \u2013, die die Navigation in den Crafting-Systemen und Dialogen f\u00fcr Nicht-Englischsprachige deutlich vereinfacht. Auch der Soundtrack verdient besondere Erw\u00e4hnung: Klassiker der 1950er und 1960er Jahre (Bob Crosby, Ella Fitzgerald, Billie Holiday usw.) sind \u00fcber die Radiosender im Spiel zu h\u00f6ren. <\/p>\n<div style=\"width: 100%\"><iframe loading=\"lazy\" width=\"100%\" height=\"500\" src=\"https:\/\/www.youtube.com\/embed\/XW7Of3g2JME\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/p>\n<p>Leider gibt es Bethesdas ber\u00fcchtigte Bugs immer noch \u2013 von urkomischen Physikfehlern bis hin zu frustrierenden Abst\u00fcrzen, insbesondere wenn man die automatische Speicherung nutzt. Die meisten Bugs werden zwar in zuk\u00fcnftigen Patches behoben, aber das Warten auf dieses Update kann die Geduld mehr auf die Probe stellen als der radioaktive Abfall selbst.<br \/>\n\n<div id=\"review\" class=\"review-wrapper wp-review-82620 wp-review-star-type wp-review-default-template wp-review-box-full-width\">\n\t\t\t<div class=\"review-heading\">\n\t\t\t<h5 class=\"review-title\">\n\t\t\t\tUrteil\n\t\t\t\t\t\t\t<\/h5>\n\t\t<\/div>\n\t\n\t\n\t\t\t<ul class=\"review-list\">\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Grafik<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:80%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Schnittstelle<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Unterhaltung<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:80%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Spielablauf<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:80%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Merkmale<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\t\n\t\t\t\t\t\t<div class=\"review-total-wrapper\">\n\t\t\t\t<span class=\"review-total-box\">4.2<\/span>\n\t\t\t\t<div class=\"review-star review-total\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:84%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"review-desc\">\n\t\t\t\t<p class=\"review-summary-title\"><strong>Zusammenfassung<\/strong><\/p>\n\t\t\t\t<p><b>Bethesda<\/b> hat wieder einmal gezeigt, dass die Formel seiner Serie sehr gut funktioniert und viele Stunden Spa\u00df und Erkundung in Szenarien der totalen Zerst\u00f6rung bietet.<\/p>\n<p>Sogar mit <b>viele Fehler<\/b> Und <b>wenig Innovation<\/b>\u201eFallout 4\u201c vereint die Eigenschaften, die Fans am Franchise am meisten m\u00f6gen, und gibt ihnen mehr Freiheit bei ihren Entscheidungen. Wenn Sie die Mischung aus <b>FPS<\/b> Und <b>Rollenspiel<\/b>.<\/p>\n<p>Ohne Zweifel: \u201e<strong>Fallout 4<\/strong>\u201e\u201c ist eine ausgezeichnete Wahl und gef\u00e4llt allen Spielertypen. Es ist jeden investierten Cent wert!<\/p>\n\t\t\t<\/div>\n\t\t\t\n\t\n\t<\/div>\n\n<style type=\"text\/css\">\n\t.wp-review-82620.review-wrapper{\n\t\twidth:100%;\n\t\toverflow:hidden;\n\t}\n\t.wp-review-82620.review-wrapper,\n\t.wp-review-82620 .review-title,\n\t.wp-review-82620 .review-desc p,\n\t.wp-review-82620 .reviewed-item p{\n\t\tcolor:#555555;\n\t}\n\t.wp-review-82620 .review-title{\n\t\tpadding-top:15px;\n\t\tfont-weight:bold;\n\t}\n\t.wp-review-82620 .review-links a{\n\t\tcolor:#f46e06;\n\t}\n\t.wp-review-82620 .review-links a:hover{\n\t\tbackground:#f46e06;\n\t\tcolor:#fff;\n\t}\n\t.wp-review-82620 .review-list li,\n\t.wp-review-82620.review-wrapper{\n\t\tbackground:#ffffff;\n\t}\n\t.wp-review-82620 .review-title,\n\t.wp-review-82620 .review-list li:nth-child(2n),\n\t.wp-review-82620 .wpr-user-features-rating .user-review-title{\n\t\tbackground:#e7e7e7;\n\t}\n\t.wp-review-82620.review-wrapper,\n\t.wp-review-82620 .review-title,\n\t.wp-review-82620 .review-list li,\n\t.wp-review-82620 .review-list li:last-child,\n\t.wp-review-82620 .user-review-area,\n\t.wp-review-82620 .reviewed-item,\n\t.wp-review-82620 .review-links,\n\t.wp-review-82620 .wpr-user-features-rating{\n\t\tborder-color:#e7e7e7;\n\t}\n\t.wp-review-82620 .wpr-rating-accept-btn{\n\t\tbackground:#f46e06;\n\t}\n\t.wp-review-82620.review-wrapper .user-review-title{\n\t\tcolor:inherit;\n\t}\n<\/style>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201eFallout 4\u201c ist der neueste Teil der beliebten Franchise und ist f\u00fcr PlayStation 4, Xbox One und PC erh\u00e4ltlich. Entwickelt von Bethesda \u2013 dem Studio hinter Skyrim \u2013 bleibt es der klassischen Formel der Serie treu, verleiht dem Spiel aber mehr \u201eFeinschliff\u201c, um das Gef\u00fchl von Freiheit im \u00d6dland zu verst\u00e4rken. Lesen Sie weiter f\u00fcr meine vollst\u00e4ndige Rezension und finden Sie heraus, ob sich der Kauf lohnt!<\/p>","protected":false},"author":1,"featured_media":82622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1281,1287],"tags":[],"class_list":["post-82620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-reviews"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2019\/11\/tfx-analise-fallout-4_review-juan-de-souza_intro.jpg?fit=1200%2C641&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8STS8-luA","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts\/82620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/comments?post=82620"}],"version-history":[{"count":3,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts\/82620\/revisions"}],"predecessor-version":[{"id":98087,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts\/82620\/revisions\/98087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/media\/82622"}],"wp:attachment":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/media?parent=82620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/categories?post=82620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/tags?post=82620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}