{"id":82362,"date":"2015-02-09T11:40:55","date_gmt":"2015-02-09T13:40:55","guid":{"rendered":"http:\/\/3.238.148.255\/?p=82362"},"modified":"2025-04-18T01:10:51","modified_gmt":"2025-04-18T00:10:51","slug":"review-far-cry-4","status":"publish","type":"post","link":"https:\/\/blog.juandesouza.com\/de\/games\/review-far-cry-4\/","title":{"rendered":"Review: Far Cry 4"},"content":{"rendered":"<p>Es ist Zeit, \u00fcber Far Cry 4 zu sprechen: ein neues Spiel der legend\u00e4ren Open-World-Reihe, die vor \u00fcber 10 Jahren mit paradiesischen Settings erschien. Der vierte Teil der Serie ist f\u00fcr PlayStation 4, Xbox One, PlayStation 3, Xbox 360 und PC erh\u00e4ltlich und hat eine vorhersehbare Mission: seinen Vorg\u00e4nger Far Cry 3, den besten Ego-Shooter des Jahres 2012, zu \u00fcbertreffen. Lest meine vollst\u00e4ndige Rezension! \ud83d\ude42<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img3.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Far Cry 4\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img3.jpg?fit=880%2C500&#038;ssl=1\" alt=\"Far Cry 4 Review Xbox One\" width=\"880\" height=\"500\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/far-cry.ubi.com\/pt-br\/home\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ubisoft<\/a><\/div>\n<\/p>\n<p>Schon in den ersten paar Minuten des Spiels wird deutlich, dass Ubisoft Montreal bei der Gestaltung der fantastischen Welt von Kyrat, einem vertikalen Paradies im Himalaya und Heimat von Pagan Min, einem Despoten, der trotz seines scheinbar harmlosen rosa Anzugs Freude am T\u00f6ten hat und sich von niemandem widersetzen l\u00e4sst, keine Details ausgelassen hat.<\/p><div id=\"juand-1897990162\" class=\"juand-content juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Der Protagonist von Far Cry 4 ist Ajay Ghale, ein junger Kyrati, der nach Hause zur\u00fcckkehrt, um den letzten Wunsch seiner verstorbenen Mutter zu erf\u00fcllen: ihre Asche in einem traditionellen Ritual an einer heiligen St\u00e4tte zu verstreuen. Doch mit einem so herzlichen Empfang hatte Ajay Ghale nicht gerechnet \u2013 im wahrsten Sinne des Wortes.<\/p>\n<p>Eigentlich war es f\u00fcr Ajay Ghale etwas zu \u201ewarm\u201c, denn unser Held wird von verschiedenen J\u00e4gern mit Granaten, Molotowcocktails und Pfeilen begr\u00fc\u00dft. Von Anfang an wusste Ajay Ghale, dass er sich mitten in einem lokalen Krieg wiederfinden w\u00fcrde, der von der k\u00f6niglichen Armee, einem Ergebnis des autorit\u00e4ren Regimes von Kyrat, angezettelt wurde.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img1.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Far Cry 4 \u2013 Grafik\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img1.jpg?fit=880%2C500&#038;ssl=1\" alt=\"Far Cry 4 Review PlayStation 4\" width=\"880\" height=\"500\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/far-cry.ubi.com\/pt-br\/home\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ubisoft<\/a><\/div>\n<\/p>\n<p>Im Laufe der Geschichte erf\u00e4hrt der Charakter, dass sein Vater den Goldenen Pfad gegr\u00fcndet hat, eine Bewegung, die Kyrats diktatorisches Regime st\u00fcrzen wollte. Im Vergleich zum Vorg\u00e4nger Far Cry 3 ist die Erz\u00e4hlung hier dichter, doch der Mangel an Charisma der Charaktere untergr\u00e4bt ihr Potenzial.<\/p>\n<p>So verbindet beispielsweise Ajay Ghale in zahlreichen Dialogen Kyrats Welt, doch sie vermitteln nie wirklich den richtigen Eindruck. Ironischerweise stammen die fesselndsten Momente aus der Feder von Pagan Min selbst \u2013 sein sadistischer Stil und seine herausragende Synchronisation heben die Qualit\u00e4t der Geschichte auf ein neues Niveau.<\/p><div id=\"juand-1086965519\" class=\"juand-content_2 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img5.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Far Cry 4 \u2013 Grafik\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img5-e1423441784163.jpg?fit=880%2C500&#038;ssl=1\" alt=\"Far Cry 4 Analyse\" width=\"880\" height=\"500\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/far-cry.ubi.com\/pt-br\/home\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ubisoft<\/a><\/div>\n<\/p>\n<p>Kyrats gesamte Karte ist au\u00dfergew\u00f6hnlich. Es ist schwer, sich an einen anderen Titel zu erinnern, der hinduistische und buddhistische Traditionen so nahtlos miteinander verbindet. Sobald Sie im fiktiven Paradies von Far Cry 4 angekommen sind, werden Sie es trotz aller Meditation nicht mehr verlassen wollen. <b>riesige Karte<\/b>.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/Gz7nsM3xhhg?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=de-DE&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>Der neueste Teil folgt der Erfolgsformel von Far Cry 3 und bietet eine immersive, erforschbare Welt, eine reiche ethnische Vielfalt und eine Tierwelt, die die fiktive s\u00fcdasiatische Umgebung perfekt einf\u00e4ngt. Schneebedeckte Bergketten, Flussebenen und \u00fcppige W\u00e4lder best\u00e4tigen, dass Far Cry 4 der beste Titel ist, den Ubisoft bisher im Franchise geschaffen hat.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img6.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Far Cry 4 \u2013 PC\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img6.jpg?fit=880%2C500&#038;ssl=1\" alt=\"Far Cry 4 PC Review\" width=\"880\" height=\"500\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/far-cry.ubi.com\/pt-br\/home\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ubisoft<\/a><\/div>\n<\/p>\n<p>Obwohl die Erkundung in Far Cry 4 dem Vorg\u00e4nger sehr \u00e4hnelt, ist der Himalaya deutlich gr\u00f6\u00dfer und f\u00fcr alle Spielertypen einladender. Unz\u00e4hlige Aktivit\u00e4ten und Missionen finden gleichzeitig auf Kyrats weitl\u00e4ufiger Karte statt.<\/p>\n<p>Es f\u00e4llt schwer, sich ausschlie\u00dflich auf die Haupthandlung zu konzentrieren, wenn man hinter jeder Ecke auf wilde Tiere oder Pagan Mins t\u00f6dliche Fallen trifft. Das Open-World-Design gibt Ihnen die Freiheit, Ihre eigenen Angriffsstrategien zu entwickeln \u2013 eine der gr\u00f6\u00dften St\u00e4rken des Spiels.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img2.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Far Cry 4 \u2013 Kyrat\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img2.jpg?fit=880%2C500&#038;ssl=1\" alt=\"Far Cry 4 Kyrat-Karte\" width=\"880\" height=\"500\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/far-cry.ubi.com\/pt-br\/home\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ubisoft<\/a><\/div>\n<\/p>\n<p>Auch die Aufgabenvielfalt in Far Cry 4 \u00fcberzeugt. Wie schon in Far Cry 3 h\u00e4utet ihr Tiere zum Basteln, hackt T\u00fcrme, um neue Gebiete freizuschalten, und zerst\u00f6rt Hunderte von Pagan Mins Propagandaplakaten, die \u00fcber Kyrat verstreut sind.<\/p><div id=\"juand-3150936779\" class=\"juand-content_3 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Um Kyrats vertikales Gel\u00e4nde besser zu bew\u00e4ltigen, gibt es jetzt einen Tragschrauber f\u00fcr schnelles Reisen \u2013 besonders praktisch beim Hacken von T\u00fcrmen. Der Enterhaken ist eine weitere willkommene Erg\u00e4nzung, mit der du Berge blitzschnell erklimmen kannst.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img7.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Far Cry 4 \u2013 Deine Strategie\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/02\/tfx-far-cry-4-img7.jpg?fit=880%2C500&#038;ssl=1\" alt=\"Far Cry 4 Gameplay\" width=\"880\" height=\"500\" \/><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/far-cry.ubi.com\/pt-br\/home\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ubisoft<\/a><\/div>\n<\/p>\n<p>Kommen wir nun zum Multiplayer-Modus. Im Koop-Modus von Far Cry 4 k\u00f6nnen Sie gemeinsam mit einem Freund im Himalaya f\u00fcr Chaos sorgen. Gemeinsam macht es noch mehr Spa\u00df, wenn Sie Ihre Taktiken koordinieren, um Herausforderungen zu meistern.<\/p>\n<p>Der kompetitive Mehrspielermodus setzt neue Ma\u00dfst\u00e4be und bietet drei Modi mit asymmetrischen K\u00e4mpfen zwischen Soldaten der k\u00f6niglichen Armee und Rebellen des Goldenen Pfads. W\u00e4hrend die Rebellen \u00fcber schwere Waffenarsenale verf\u00fcgen, kann die k\u00f6nigliche Seite Bestien beschw\u00f6ren und sich auf t\u00f6dliche B\u00f6gen verlassen.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"880\" height=\"495\" src=\"https:\/\/www.youtube.com\/embed\/rlo5Mrc3wOw?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=de-DE&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n\n<div id=\"review\" class=\"review-wrapper wp-review-82362 wp-review-star-type wp-review-default-template wp-review-box-full-width\">\n\t\t\t<div class=\"review-heading\">\n\t\t\t<h5 class=\"review-title\">\n\t\t\t\tUrteil\n\t\t\t\t\t\t\t<\/h5>\n\t\t<\/div>\n\t\n\t\n\t\t\t<ul class=\"review-list\">\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Grafik<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Schnittstelle<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Unterhaltung<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Spielablauf<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Merkmale<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\t\n\t\t\t\t\t\t<div class=\"review-total-wrapper\">\n\t\t\t\t<span class=\"review-total-box\">4.7<\/span>\n\t\t\t\t<div class=\"review-star review-total\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:94%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"review-desc\">\n\t\t\t\t<p class=\"review-summary-title\"><strong>Zusammenfassung<\/strong><\/p>\n\t\t\t\t<p>Far Cry 4 zeigt sein volles Potenzial und seine offene Welt vom ersten Durchspielen an. Es beh\u00e4lt alle gelobten Elemente bei, die Far Cry ber\u00fchmt gemacht haben, integriert aber wichtige Neuerungen in die riesige offene Welt, wie abwechslungsreiche Umgebungen und ein fesselndes und faszinierendes mystisches Thema. Zwar vermittelt Ajay Ghales Reise das Gef\u00fchl, eine \u00e4hnliche Situation bereits erlebt zu haben (wie in Far Cry 3), dennoch macht das Spiel Spa\u00df und ist unterhaltsam. Die Handlung k\u00f6nnte etwas besser sein, ist aber akzeptabel und interessant.<\/p>\n\t\t\t<\/div>\n\t\t\t\n\t\n\t<\/div>\n\n<style type=\"text\/css\">\n\t.wp-review-82362.review-wrapper{\n\t\twidth:100%;\n\t\toverflow:hidden;\n\t}\n\t.wp-review-82362.review-wrapper,\n\t.wp-review-82362 .review-title,\n\t.wp-review-82362 .review-desc p,\n\t.wp-review-82362 .reviewed-item p{\n\t\tcolor:#555555;\n\t}\n\t.wp-review-82362 .review-title{\n\t\tpadding-top:15px;\n\t\tfont-weight:bold;\n\t}\n\t.wp-review-82362 .review-links a{\n\t\tcolor:#f46e06;\n\t}\n\t.wp-review-82362 .review-links a:hover{\n\t\tbackground:#f46e06;\n\t\tcolor:#fff;\n\t}\n\t.wp-review-82362 .review-list li,\n\t.wp-review-82362.review-wrapper{\n\t\tbackground:#ffffff;\n\t}\n\t.wp-review-82362 .review-title,\n\t.wp-review-82362 .review-list li:nth-child(2n),\n\t.wp-review-82362 .wpr-user-features-rating .user-review-title{\n\t\tbackground:#e7e7e7;\n\t}\n\t.wp-review-82362.review-wrapper,\n\t.wp-review-82362 .review-title,\n\t.wp-review-82362 .review-list li,\n\t.wp-review-82362 .review-list li:last-child,\n\t.wp-review-82362 .user-review-area,\n\t.wp-review-82362 .reviewed-item,\n\t.wp-review-82362 .review-links,\n\t.wp-review-82362 .wpr-user-features-rating{\n\t\tborder-color:#e7e7e7;\n\t}\n\t.wp-review-82362 .wpr-rating-accept-btn{\n\t\tbackground:#f46e06;\n\t}\n\t.wp-review-82362.review-wrapper .user-review-title{\n\t\tcolor:inherit;\n\t}\n<\/style>","protected":false},"excerpt":{"rendered":"<p>Es ist Zeit, \u00fcber Far Cry 4 zu sprechen: ein neues Spiel der legend\u00e4ren Open-World-Reihe, die vor \u00fcber 10 Jahren mit paradiesischen Settings erschien. Der vierte Teil der Serie ist f\u00fcr PlayStation 4, Xbox One, PlayStation 3, Xbox 360 und PC erh\u00e4ltlich und hat eine vorhersehbare Mission: seinen Vorg\u00e4nger Far Cry 3, den besten Ego-Shooter des Jahres 2012, zu \u00fcbertreffen. Lest meine vollst\u00e4ndige Rezension!<\/p>","protected":false},"author":1,"featured_media":82364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1281,1287],"tags":[],"class_list":["post-82362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-reviews"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2019\/10\/tfx-review-far-cry-4-analise-intro-tfxbrasil.jpg?fit=1200%2C675&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8STS8-lqq","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts\/82362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/comments?post=82362"}],"version-history":[{"count":4,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts\/82362\/revisions"}],"predecessor-version":[{"id":97924,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts\/82362\/revisions\/97924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/media\/82364"}],"wp:attachment":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/media?parent=82362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/categories?post=82362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/tags?post=82362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}