{"id":82335,"date":"2015-07-11T09:42:27","date_gmt":"2015-07-11T12:42:27","guid":{"rendered":"http:\/\/3.238.148.255\/?p=82335"},"modified":"2025-04-14T17:26:00","modified_gmt":"2025-04-14T16:26:00","slug":"review-titanfall","status":"publish","type":"post","link":"https:\/\/blog.juandesouza.com\/de\/games\/review-titanfall\/","title":{"rendered":"Review: Titanfall"},"content":{"rendered":"<p>Titanfall ist der neueste Ego-Shooter aus der Partnerschaft zwischen Electronic Arts und Respawn Entertainment. Das Spiel erscheint als einer der ersten Titel f\u00fcr die Xbox One, zus\u00e4tzlich zu Versionen f\u00fcr Xbox 360 und PC. Kann Titanfall als FPS wirklich \u00fcberzeugen? Hier erfahren Sie es!<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/07\/tfx-review-titanfall_img1.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Titanfall\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/07\/tfx-review-titanfall_img1.jpg?w=880&#038;ssl=1\" alt=\"Titanfall-Analyse Xbox Brasilien\" ><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/www.denofgeek.com\/games\/titanfall\/27002\/titanfall-gameplay-demo\" target=\"_blank\" rel=\"noopener noreferrer\">H\u00f6hle des Geeks<\/a><\/div>\n<\/p>\n<p>Titanfall beginnt seine eigene \u201eRevolution\u201c gleich von Anfang an, indem es auf einen traditionellen Kampagnenmodus verzichtet \u2013 ein Feature, das bereits in anderen Spielen implementiert wurde, wie zum Beispiel <a href=\"http:\/\/www.tfxbrasil.com\/2014\/07\/review-plants-vs-zombies-garden-warfare.html\" target=\"_blank\" rel=\"noopener noreferrer\">Pflanzen gegen Zombies: Garden Warfare<\/a>Stattdessen konzentriert sich der ganze Glanz des Spiels ausschlie\u00dflich auf den Mehrspielermodus, in dem die wahre Action darauf wartet, entdeckt zu werden.<\/p><div id=\"juand-3750087870\" class=\"juand-content juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p>Zu Beginn des Spiels wird ein \u00e4u\u00dferst detailliertes Tutorial gestartet, das alle neuen Funktionen erkl\u00e4rt \u2013 vom einfachen Doppelsprung und Wandlaufen bis hin zur Steuerung der Titanen und deren F\u00e4higkeiten. F\u00fcr Neulinge gibt es keine bessere M\u00f6glichkeit, sich mit der Steuerung vertraut zu machen. Wer jedoch an der Beta-Phase teilgenommen hat, muss diese Aufgaben erneut durchlaufen.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/07\/tfx-review-titanfall_img2.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Titanfall\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/07\/tfx-review-titanfall_img2.jpg?w=880&#038;ssl=1\" alt=\"Xbox One Titanfall Review\" ><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/teambeyond.net\/titanfall-gameplay\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mehr als nur Unterhaltung<\/a><\/div>\n<\/p>\n<p>Als N\u00e4chstes m\u00fcssen Sie einen der vordefinierten Spielmodi ausw\u00e4hlen, um zu beginnen. Der Mehrspielermodus enth\u00e4lt zwar einige kurze Zwischensequenzen, um die Geschichte nicht komplett zu verwerfen, ersetzt jedoch die komplexe, detaillierte Geschichte durch Mehrspielerpartien, in denen Sie unabh\u00e4ngig vom Endergebnis immer weiterkommen.<\/p>\n<p>Insgesamt gibt es 18 Level, die auf recht gro\u00dfen und spieltypischen Karten stattfinden. Das Fehlen einer tiefgr\u00fcndigen Story ist \u2013 insbesondere bei einem Spiel, das auf Online-Spiele ausgerichtet ist \u2013 kein wirkliches Problem. Im Gegenteil, das Spielerlebnis kann sogar als gute Vorbereitung auf die Herausforderungen dienen, die auch in den traditionellen Modi zu finden sind.<\/p>\n<p>Nach der Auswahl der gew\u00fcnschten Karte gelangen die Spieler in eine Lobby, in der Teams und Anpassungsoptionen angezeigt werden. Trotz einiger Probleme am Starttag funktioniert das bekannte \u201eMatchmaking\u201c recht z\u00fcgig \u2013 insbesondere im Attrition-Modus, in dem sich die schiere Masse an Spielern im wahrsten Sinne des Wortes ansammelt.<\/p><div id=\"juand-845070219\" class=\"juand-content_2 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/07\/tfx-review-titanfall_img3.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Titanfall\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/07\/tfx-review-titanfall_img3.jpg?w=880&#038;ssl=1\" alt=\"Titanfall Xbox herunterladen\" ><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/titanfall.wikia.com\/wiki\/File:Titanfall_Expedition_Gameplay_Trailer\" target=\"_blank\" rel=\"noopener noreferrer\">Titanfall Wiki<\/a><\/div>\n<\/p>\n<p>In Titanfall sind die Teams auf maximal sechs Spieler begrenzt. Die Karten sind jedoch voller Gegner, die f\u00fcr echte Spieler eine leichte Beute darstellen. Jeder erzielte Punkt verk\u00fcrzt den Countdown um einige Sekunden und belohnt die Spieler f\u00fcr ihre Leistung mit der vorzeitigen Ankunft ihrer gigantischen Maschinen.<\/p>\n<p>Beim Spielen von Titanfall f\u00e4llt auf, dass sich die \u201eTitanen\u201c sehr nat\u00fcrlich und realistisch bewegen. Ihre Spr\u00fcnge erm\u00f6glichen beispielsweise Angriffe, die f\u00fcr schnellere Fortbewegung und\/oder zum Rammen kleinerer Gegner genutzt werden k\u00f6nnen. Dar\u00fcber hinaus verf\u00fcgen die Titan-Modelle \u00fcber besondere Eigenschaften \u2013 beispielsweise einzigartige F\u00e4higkeiten und ein hohes Gewicht \u2013, die ihre Steuerung und Leistung stark beeinflussen.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/07\/tfx-review-titanfall_img4.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" title=\"Review: Titanfall\" src=\"https:\/\/i0.wp.com\/cdn.tfx.company\/app\/coliseugeek\/sites\/tfxbrasil\/wp-content\/uploads\/2015\/07\/tfx-review-titanfall_img4.jpg?w=880&#038;ssl=1\" alt=\"Titanfall PC-Test\" ><\/a><\/div>\n<div style=\"text-align: center;\">Bildquelle: <a href=\"http:\/\/titanfall.wikia.com\/wiki\/File:Titanfall_Expedition_Gameplay_Trailer\" target=\"_blank\" rel=\"noopener noreferrer\">Titanfall Wiki<\/a><\/div>\n<\/p>\n<p>Wie in vielen gro\u00dfen FPS-Spielen generieren Matches Erfahrung, die neue Freischaltungen erm\u00f6glicht \u2013 sowohl f\u00fcr Titanen als auch f\u00fcr die Soldaten. Im Laufe jedes Matches haben Spieler Zugriff auf eine wachsende Auswahl an Waffen, Ausr\u00fcstung und F\u00e4higkeiten. So kommt man kaum ins Stocken, denn die M\u00f6glichkeiten sind riesig.<\/p>\n<p>Titanfall verf\u00fcgt au\u00dferdem \u00fcber ein \u201eintelligentes\u201c Kartensystem, mit dem w\u00e4hrend eines Spiels bestimmte F\u00e4higkeiten oder besondere Gegenst\u00e4nde f\u00fcr die Spieler aktiviert werden k\u00f6nnen. Ein interessanter Aspekt ist beispielsweise die M\u00f6glichkeit, ein hochpr\u00e4zises Gewehr zu erhalten oder den Charakter in bestimmten Momenten etwas schneller laufen zu lassen.<\/p>\n<p>Optisch, Titanfall <strong>steigt<\/strong> Ein weiterer Schritt in dieser Kategorie, ohne zu versagen. Noch wichtiger ist, dass das Spiel trotz der zahlreichen Gegner, Explosionen, Lichteffekte und riesigen Roboter weder unter Rucklern noch nennenswerten Einbr\u00fcchen der Frames pro Sekunde (FPS) leidet.<\/p><div id=\"juand-1676282923\" class=\"juand-content_3 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<div style=\"width: 100%\"><iframe loading=\"lazy\" width=\"100%\" height=\"500\" src=\"https:\/\/www.youtube.com\/embed\/GjwxXKXr_jk\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<p>Die Soundeffekte in Titanfall sind eine Show f\u00fcr sich, besonders mit einem Headset oder hochwertigen Kopfh\u00f6rern. Zudem sind die Schl\u00e4ge der Roboterk\u00e4mpfe auch aus der Ferne gut h\u00f6rbar. Das Sounddesign der Waffen und der Umgebungen ist sorgf\u00e4ltig ausgearbeitet, was dem Titan-Spieler deutlich sp\u00fcrbar und von Vorteil ist.<\/p>\n\n<div id=\"review\" class=\"review-wrapper wp-review-82335 wp-review-star-type wp-review-default-template wp-review-box-full-width\">\n\t\t\t<div class=\"review-heading\">\n\t\t\t<h5 class=\"review-title\">\n\t\t\t\tUrteil\n\t\t\t\t\t\t\t<\/h5>\n\t\t<\/div>\n\t\n\t\n\t\t\t<ul class=\"review-list\">\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Grafik<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:80%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Schnittstelle<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Unterhaltung<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:80%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t<span>Spielablauf<\/span>\n\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\t\n\t\t\t\t\t\t<div class=\"review-total-wrapper\">\n\t\t\t\t<span class=\"review-total-box\">4.3<\/span>\n\t\t\t\t<div class=\"review-star review-total\">\n\t<div class=\"review-result-wrapper\" style=\"color: #95bae0;\">\n\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:86%; color:#f46e06;\">\n\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"mts-icon-star\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"review-desc\">\n\t\t\t\t<p class=\"review-summary-title\"><strong>Zusammenfassung<\/strong><\/p>\n\t\t\t\t<p>Titanfall hat sich das Warten (einschlie\u00dflich der Aufnahme des Spiels f\u00fcr EA Access-Abonnenten) und die damit verbundene Vorfreude gelohnt. Mit extrem ausgewogener und unterhaltsamer Spielmechanik, pr\u00e4zisem und fl\u00fcssigem Gameplay und erstklassiger Performance bietet Titanfall zudem eine explosive Mischung aus traditionellem Shooter-Genre, die hervorragend umgesetzt ist. Zweifellos ist Titanfall die damit verbundene Vorfreude wert.<\/p>\n\t\t\t<\/div>\n\t\t\t\n\t\n\t<\/div>\n\n<style type=\"text\/css\">\n\t.wp-review-82335.review-wrapper{\n\t\twidth:100%;\n\t\toverflow:hidden;\n\t}\n\t.wp-review-82335.review-wrapper,\n\t.wp-review-82335 .review-title,\n\t.wp-review-82335 .review-desc p,\n\t.wp-review-82335 .reviewed-item p{\n\t\tcolor:#555555;\n\t}\n\t.wp-review-82335 .review-title{\n\t\tpadding-top:15px;\n\t\tfont-weight:bold;\n\t}\n\t.wp-review-82335 .review-links a{\n\t\tcolor:#f46e06;\n\t}\n\t.wp-review-82335 .review-links a:hover{\n\t\tbackground:#f46e06;\n\t\tcolor:#fff;\n\t}\n\t.wp-review-82335 .review-list li,\n\t.wp-review-82335.review-wrapper{\n\t\tbackground:#ffffff;\n\t}\n\t.wp-review-82335 .review-title,\n\t.wp-review-82335 .review-list li:nth-child(2n),\n\t.wp-review-82335 .wpr-user-features-rating .user-review-title{\n\t\tbackground:#e7e7e7;\n\t}\n\t.wp-review-82335.review-wrapper,\n\t.wp-review-82335 .review-title,\n\t.wp-review-82335 .review-list li,\n\t.wp-review-82335 .review-list li:last-child,\n\t.wp-review-82335 .user-review-area,\n\t.wp-review-82335 .reviewed-item,\n\t.wp-review-82335 .review-links,\n\t.wp-review-82335 .wpr-user-features-rating{\n\t\tborder-color:#e7e7e7;\n\t}\n\t.wp-review-82335 .wpr-rating-accept-btn{\n\t\tbackground:#f46e06;\n\t}\n\t.wp-review-82335.review-wrapper .user-review-title{\n\t\tcolor:inherit;\n\t}\n<\/style>","protected":false},"excerpt":{"rendered":"<p>Titanfall ist der neueste Ego-Shooter aus der Partnerschaft zwischen Electronic Arts und Respawn Entertainment. Das Spiel erscheint als einer der ersten Titel f\u00fcr die Xbox One, zus\u00e4tzlich zu Versionen f\u00fcr Xbox 360 und PC. Kann Titanfall als FPS wirklich \u00fcberzeugen? Hier erfahren Sie es!<\/p>","protected":false},"author":1,"featured_media":82336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1281,1287],"tags":[],"class_list":["post-82335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-reviews"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2019\/10\/tfx-game-titanfall-review-intro.jpg?fit=1920%2C1080&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8STS8-lpZ","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts\/82335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/comments?post=82335"}],"version-history":[{"count":2,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts\/82335\/revisions"}],"predecessor-version":[{"id":97831,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/posts\/82335\/revisions\/97831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/media\/82336"}],"wp:attachment":[{"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/media?parent=82335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/categories?post=82335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/de\/wp-json\/wp\/v2\/tags?post=82335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}