{"id":84387,"date":"2025-03-19T21:12:51","date_gmt":"2025-03-19T21:12:51","guid":{"rendered":"http:\/\/54.90.224.147\/?p=84387"},"modified":"2025-03-22T23:45:24","modified_gmt":"2025-03-22T23:45:24","slug":"descubra-como-e-feita-a-gravacao-dos-bastidores-de-just-dance","status":"publish","type":"post","link":"https:\/\/blog.juandesouza.com\/br\/games\/descubra-como-e-feita-a-gravacao-dos-bastidores-de-just-dance\/","title":{"rendered":"Descubra como s\u00e3o feitas as grava\u00e7\u00f5es dos bastidores de Just Dance!"},"content":{"rendered":"<p class=\"\" data-start=\"63\" data-end=\"221\">Voc\u00ea certamente j\u00e1 viu, ouviu falar ou jogou <em data-start=\"110\" data-end=\"122\">Apenas dance<\/em> em algum momento \u2014 \u00e9 simplesmente um dos jogos mais incr\u00edveis j\u00e1 criados e mantidos pela Ubisoft.<\/p>\n<p class=\"\" data-start=\"223\" data-end=\"536\">Eu, pessoalmente, j\u00e1 joguei v\u00e1rias vezes, passei vergonha algumas vezes e at\u00e9 levei alguns tombos, mas o resultado final vale totalmente a pena. Mas voc\u00ea j\u00e1 parou para pensar: como \u00e9 feita a grava\u00e7\u00e3o nos bastidores do <em data-start=\"447\" data-end=\"459\">Apenas dance<\/em>, tamb\u00e9m conhecido como o que acontece nos bastidores? Bem, confira todos os detalhes aqui!<\/p><div id=\"juand-137456444\" class=\"juand-content juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p><\/p>\n<p class=\"\" data-start=\"538\" data-end=\"981\"><em data-start=\"538\" data-end=\"550\">Apenas dance<\/em> tem sido um sucesso h\u00e1 anos, n\u00e3o apenas por ser um jogo divertido e energ\u00e9tico, mas tamb\u00e9m pela tecnologia e criatividade que entram em sua produ\u00e7\u00e3o. Por tr\u00e1s de cada movimento de dan\u00e7a perfeito que voc\u00ea v\u00ea na tela, h\u00e1 um processo complexo envolvendo captura de movimento, coreografia e tempo preciso. Embora possa parecer f\u00e1cil quando voc\u00ea est\u00e1 se divertindo jogando, na verdade h\u00e1 muito trabalho duro e inova\u00e7\u00e3o acontecendo por tr\u00e1s desses movimentos brilhantes.<\/p>\n<p class=\"\" data-start=\"983\" data-end=\"1379\">Neste post, reuni alguns v\u00eddeos interessantes que mostram exatamente como esse processo se desenrola, desde as v\u00e1rias edi\u00e7\u00f5es do <em data-start=\"1108\" data-end=\"1120\">Apenas dance<\/em>\u2014come\u00e7ando de <em data-start=\"1135\" data-end=\"1152\">Apenas Dance 2016<\/em> at\u00e9 o \u00faltimo lan\u00e7amento, <em data-start=\"1188\" data-end=\"1205\">Apenas Dance 2021<\/em>. Se voc\u00ea j\u00e1 se perguntou sobre os detalhes meticulosos envolvidos na cria\u00e7\u00e3o das sequ\u00eancias de dan\u00e7a impressionantes e a magia por tr\u00e1s do jogo, esses v\u00eddeos oferecem uma vis\u00e3o fascinante.<\/p>\n<h3>Apenas Dance 2016<\/h3>\n<div style=\"width: 100%;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Xg5ajToIUoM\" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<h3>Apenas Dance 2017<\/h3>\n<div style=\"width: 100%;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/u0EbaCynCxc\" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<h3>Apenas Dance 2018<\/h3>\n<div style=\"width: 100%;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/33EhZoLroyE\" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<h3>Apenas Dance 2019<\/h3>\n<div style=\"width: 100%;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/8WIOv1Pcuig\" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p class=\"\" data-start=\"1552\" data-end=\"2022\">Cada ano traz algo novo para a mesa. A coreografia melhora, os dan\u00e7arinos ficam mais din\u00e2micos e a tecnologia por tr\u00e1s da captura de movimento se torna ainda mais precisa. Nos primeiros dias, o processo era relativamente simples, mas conforme o jogo evoluiu, a complexidade dos movimentos tamb\u00e9m evoluiu. A adi\u00e7\u00e3o de sensores de movimento mais sofisticados e software avan\u00e7ado permitiu que a equipe de desenvolvimento criasse movimentos de dan\u00e7a mais realistas e fluidos que tornam o jogo t\u00e3o envolvente.<\/p>\n<p class=\"\" data-start=\"2024\" data-end=\"2372\">A magia de <em data-start=\"2037\" data-end=\"2049\">Apenas dance<\/em> reside em como os criadores combinam coreografias de dan\u00e7a da vida real com ferramentas de alta tecnologia. Os dan\u00e7arinos executam movimentos complexos enquanto s\u00e3o gravados em est\u00fadios de captura de movimento, onde cada movimento \u00e9 traduzido para o jogo. Essa filmagem \u00e9 ent\u00e3o usada para criar personagens virtuais que voc\u00ea, como jogador, ver\u00e1 na tela.<\/p><div id=\"juand-2779246874\" class=\"juand-content_2 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>\n<p class=\"\" data-start=\"2374\" data-end=\"2700\">Mas h\u00e1 mais do que apenas captura de movimento envolvida. As trilhas sonoras, ilumina\u00e7\u00e3o, \u00e2ngulos de c\u00e2mera e at\u00e9 mesmo as roupas dos dan\u00e7arinos s\u00e3o cuidadosamente escolhidas e projetadas para aprimorar a experi\u00eancia. Cada aspecto do jogo \u00e9 meticulosamente planejado para trazer a experi\u00eancia mais divertida e envolvente poss\u00edvel para jogadores de todas as idades.<\/p>\n<h3>Apenas Dance 2020<\/h3>\n<div style=\"width: 100%;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/2fdJtHX9sVc\" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<h3>Apenas Dance 2021<\/h3>\n<div style=\"width: 100%;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/TxUEU9ypsU8\" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<p class=\"\" data-start=\"2702\" data-end=\"3139\">O que \u00e9 fascinante \u00e9 como <em data-start=\"2728\" data-end=\"2740\">Apenas dance<\/em> conseguiu acompanhar as \u00faltimas tend\u00eancias em m\u00fasica e dan\u00e7a. A cada nova edi\u00e7\u00e3o, os desenvolvedores certamente incorporar\u00e3o as faixas mais quentes, e eles trazem uma gama diversificada de artistas e performers para mostrar diferentes estilos de dan\u00e7a, tornando o jogo ainda mais inclusivo e emocionante. Do hip-hop ao pop, da m\u00fasica latina \u00e0 cl\u00e1ssica, h\u00e1 sempre algo novo para aprender e curtir.<\/p>\n<p class=\"\" data-start=\"3141\" data-end=\"3460\">O sucesso cont\u00ednuo do jogo mostra o qu\u00e3o bem os desenvolvedores entendem seu p\u00fablico. Eles sabem que as pessoas n\u00e3o querem apenas dan\u00e7ar, mas tamb\u00e9m querem sentir que s\u00e3o parte da performance, e \u00e9 a\u00ed que entra a m\u00e1gica da captura de movimento. \u00c9 tudo sobre fazer voc\u00ea sentir como se estivesse dan\u00e7ando ao lado das estrelas.<\/p>\n<p class=\"\" data-start=\"3462\" data-end=\"3820\">E voc\u00ea? Voc\u00ea j\u00e1 se perguntou sobre o processo de bastidores da cria\u00e7\u00e3o de <em data-start=\"3553\" data-end=\"3565\">Apenas dance<\/em>? Voc\u00ea gosta da dan\u00e7a e dos desafios que ela traz, ou j\u00e1 passou por uma falha engra\u00e7ada ao tentar acompanhar a coreografia? Eu adoraria ouvir suas opini\u00f5es sobre como o jogo \u00e9 feito e como voc\u00ea se sente sobre sua progress\u00e3o ao longo dos anos!<\/p>\n<p class=\"\" data-start=\"3822\" data-end=\"3945\">Confira o processo completo nos bastidores e me diga o que voc\u00ea acha. N\u00e3o \u00e9 apenas um jogo; \u00e9 uma revolu\u00e7\u00e3o da dan\u00e7a!<\/p><div id=\"juand-3854948180\" class=\"juand-content_3 juand-entity-placement\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-8944986240478060\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n style=\"display:block; text-align:center;\"\r\n data-ad-layout=\"in-article\"\r\n data-ad-format=\"fluid\"\r\n data-ad-client=\"ca-pub-8944986240478060\"\r\n data-ad-slot=\"9601515663\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>You\u2019ve definitely seen, heard about, or played Just Dance at some point\u2014it&#8217;s simply one of the most incredible games ever created and maintained by Ubisoft. Personally, I\u2019ve played it many times, embarrassed myself a few times, and even taken some falls, but the final result is totally worth it. But have you ever stopped to [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":84389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1281],"tags":[4558,4560],"class_list":["post-84387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","tag-home","tag-ubisoft"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.juandesouza.com\/wp-content\/uploads\/2021\/06\/coliseugeek-como-funciona-justdance-gravacoes-chroma-key2.jpg?fit=1920%2C1080&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8STS8-lX5","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/posts\/84387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/comments?post=84387"}],"version-history":[{"count":2,"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/posts\/84387\/revisions"}],"predecessor-version":[{"id":97165,"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/posts\/84387\/revisions\/97165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/media\/84389"}],"wp:attachment":[{"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/media?parent=84387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/categories?post=84387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.juandesouza.com\/br\/wp-json\/wp\/v2\/tags?post=84387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}